


{"id":62064,"date":"2026-05-12T14:54:56","date_gmt":"2026-05-12T17:54:56","guid":{"rendered":"https:\/\/www.veeva.com\/br\/?page_id=62064"},"modified":"2026-09-01T15:22:29","modified_gmt":"2026-09-01T18:22:29","slug":"crm-suite","status":"publish","type":"page","link":"https:\/\/pantheon.veeva.com\/br\/products\/crm-suite\/","title":{"rendered":"Veeva Vault CRM Suite"},"content":{"rendered":"<style>\n<p>.veeva-2024  #hero.hero-centered--image {\n--mobile-image: url(https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/veeva-2024\/background\/suite-hero-mobile.jpg);\n--desktop-image: url(https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/veeva-2024\/background\/suite-hero-desktop.jpg);\n}<\/p>\n<p>\/* Z Pattern - Products Customer CSS *\/\n.veeva-2024 .side-line h4 {\n\tmargin-top:45px;\n\tborder-left:2px solid #f7981d;\n\tpadding-left:12px\n}\n.veeva-2024 .side-line p {\n\tpadding-left:13px;\n\tfont-size: 18px;\n\tline-height: 140%;\n\tcolor: #636669;\n}\n\/* The Power of Connected CSS *\/<\/p>\n<p>.veeva-2024 .listed-up-card {\n\tpadding: 0px 28px;\n}<\/p>\n<p>@media (min-width:991px) {\n\t.veeva-2024 .listed-up-card {\n\t\tmax-width: 469px;\n\t\tpadding: 32px 28px;\n\t}\n}<\/p>\n<p>.veeva-2024 .impact-card h6 {\n\tfont-size:18px;\n\tmargin-bottom:15px;\n}\n.veeva-2024 .impact-card p {\n\tfont-size:14px;\n\tfont-weight:400;\n\tcolor: #636669;\n}\n.veeva-2024 .border-box {\n\tmax-width:1300px;\n\tpadding: 60px;\n\ttext-align:center;\n\tgap: 10px;\n\tborder-radius: 40px;\n\tbackground: #eef1f5;\n\tbox-shadow: 0px 5px 8px 0px rgba(0, 0, 0, 0.15);\n\tmargin:30px;\n\tmargin-top:60px;<\/p>\n<p>}\n@media (min-width:991px) {\n\t.veeva-2024 .border-box {\t\t\n\t\tmargin:30px;\n\t\tmargin-top:80px;\n\t}\n}\n@media (min-width:1300px) {\n\t.veeva-2024 .border-box {\n\t\tmargin:30px auto;\n\t\tmargin-top:100px;\n\t}\n}\n@media (min-width:1200px) {\n\t.veeva-2024 .listed-up-impact__cards {\n\t\tgap: 32px;\n\t\tgrid-template-columns: repeat(4,1fr);\n\t}\n}\n@media (min-width:576px) {\n.veeva-2024 .impact-card {\nmax-width: 392px;\ntext-align: left;\n}\n}\n.veeva-2024 .impact-card p {\ncolor: #636669;\nmargin-bottom: 0rem;\n}<\/p>\n<p>.veeva-2024 .impact-card .card-arrow {\n\tborder: none;\n\tborder:2px solid black;\n\twidth: 40px;\n\tmargin: auto;\n\tmargin-top: 10px;\n\tdisplay: block;\n\tborder-radius: 50%;\n\tvertical-align: middle;\n}\n@media (min-width:576px) {\n.veeva-2024 .impact-card .card-arrow {\t\n\tmargin: unset;\n\tmargin-top: 15px;\n\tvertical-align: left;\n}\n}<\/p>\n<p>\/* Quotes and Logos Customer CSS *\/<\/p>\n<p>.veeva-2024 .logo-wall-listed--dark {\n\tbackground: none;\n}\n.veeva-2024 .quote-tabs--dark {\n\tbackground:none;\n}<\/p>\n<p>@media (min-width:992px) {\n\t.veeva-2024 .quote-card-full {\n\t\tmin-height: 350px;\n\t\tpadding: 50px;\n\t\tdisplay:flex;\n\t}\n}<\/p>\n<p>.veeva-2024 .main-quote-row {\n\twidth:100%;\n\tdisplay:flex;\n\talign-items: center;\n}\n.veeva-2024 .quote-card .headshot {\n\tfloat:none;\n\twidth:100%;\n\tmax-width:380px;border-radius: 24px;\n\tmargin:20px auto 0 10px;\n} \n.veeva-2024 .quote-card-full p {\n\tfont-size: 26px;\n\tfont-style: normal;\n\tfont-weight: 600;\n\tline-height: 120%; \/* 38.4px *\/\n\tletter-spacing: -0.96px;\n}\n.veeva-2024 .quote-card-full h5, .veeva-2024 .quote-card-full h6 {\n\tfont-style: normal;\n\tfont-weight: 600;\n\tline-height: 140%; \/* 28px *\/\n\tletter-spacing: -0.6px;\n\tmargin-top:24px;\n}\n.veeva-2024 .quote-card-full h6 {\n\tfont-style: normal;\n\tfont-weight: 400!important;\n\tmargin-top:5px!important;\n\tmargin-bottom:30px!important;\n}\n.veeva-2024 .quote-card-full .quote-content {\n\ttext-align:center;\n\tpadding-bottom:30px;\n}\n@media (min-width:991px) {\n\t.veeva-2024 .quote-card .headshot {\n\t\tfloat:right;\n\t\twidth:100%;\n\t\tmax-width:420px;border-radius: 24px;\n\t\tmargin:20px 0;\n\t} \n\t.veeva-2024 .quote-card-full p {\n\t\tfont-size: 32px;\n\t\tfont-style: normal;\n\t\tfont-weight: 600;\n\t\tline-height: 120%; \/* 38.4px *\/\n\t\tletter-spacing: -0.96px;\n\t}\n\t.veeva-2024 .quote-card-full h5, .veeva-2024 .quote-card-full h6  {\n\t\tfont-size: 20px;\n\t\tfont-style: normal;\n\t\tfont-weight: 600;\n\t\tline-height: 140%; \/* 28px *\/\n\t\tletter-spacing: -0.6px;\n\t\tmargin-top:24px;\n\t}\n\t.veeva-2024 .quote-card-full .quote-content {\n\t\ttext-align:left;\n\t\tpadding-right:30px;\n\t}\n} <\/p>\n<p>@media (min-width:992px) {\n.veeva-2024 .z-pattern-products .z-pattern__wrapper.products {\ngrid-template-columns: 1fr;\npadding-top: 70px;\n}\n}<\/p>\n<p>@media (min-width:768px) {\n.veeva-2024 .products .z-pattern__subgrid {\ngrid-template-columns: 1fr 1fr;\n}\n}\n@media (min-width:991px) {\n.veeva-2024 .products .z-pattern__subgrid {\ngrid-template-columns: 1fr 1fr 1fr 1fr;\n}\n}<\/p>\n<p>\/* Resources Custom CSS *\/<\/p>\n<p>.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:first-child .resource-card__text, .veeva-2024 .resource-card.resource-card--featured--main .resource-card__text {\n\tmin-height: 90px;\n}\n.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:nth-child(2), .veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:nth-child(3) {\n\tmin-height: 90px;\n}\n.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card {\n\tmin-height: 90px;\n}\n.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:first-child .resource-card__media--bg img, .veeva-2024 .resource-card.resource-card--featured--main .resource-card__media--bg img {\n\theight: calc(100% - 3.5rem);\n\ttop: 2rem;\n}<\/p>\n<p>@media (min-width:991px){<\/p>\n<p>\t.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:first-child .resource-card__text h5{\n\t\tmin-height: 180px;\n\t}\n\t.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:nth-child(2), .veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:nth-child(3) {\n\t\tmin-height: 180px;\n\t}\n\t.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card {\n\t\tmin-height: 180px;\n\t}<\/p>\n<p>}\n@media (min-width:1200px) {\n\t.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:first-child .resource-card__text .h5, .veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:first-child .resource-card__text h5, .veeva-2024 .resource-card.resource-card--featured--main .resource-card__text .h5, .veeva-2024 .resource-card.resource-card--featured--main .resource-card__text h5 {\n\t\tmax-width: 600px;\n\t}\n}\n@media (max-width:768px){\n.veeva-2024 .resource-block-featured .resource-card .resource-card__text {\njustify-content: center;\n}\n}<\/p>\n<p>.veeva-2024 .resource-block-featured .resource-card .button-secondary {\n\tposition:absolute;\n\tbottom:20px;\n}\n@media (min-width:992px) {\n.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:first-child .resource-card__text, .veeva-2024 .resource-card.resource-card--featured--main .resource-card__text {\n\t\tpadding-left: 3rem;\n\t}\n}\n@media (max-width:991px) {\n.veeva-2024 .resource-block-featured .resource-card .resource-card__text h5\n {\nfont-size: 16px!important;\n}\n}\n.veeva-2024 .resource-card__text .button-secondary img {\nbackground-color: white;\n}\n.veeva-2024 .copy-container--eyebrow-gradient .icon {\nbackground: black;\n}\n.veeva-2024 .impact-card img {\t\t\t\nheight: 15px;\t\n}\t<\/p>\n<p>@media (min-width:768px) {\n.veeva-2024 .h1, .veeva-2024 h1 {\nfont-size: 48px;\n}\n}<\/p>\n<p>@media (min-width:768px) {\n.veeva-2024 .z-pattern__image-wrapper {\nborder-radius: 0px;\n}\n}<\/p>\n<p>.veeva-2024 .impact-card:hover h6 {\ncolor:#f7981d;\n}<\/p>\n<p>@media (min-width:1200px) {\n.veeva-2024 .z-pattern__subgrid {\ngap: 28px 32px;\n}\n}\n.veeva-2024 .impact-card-linkout span.icon {\nheight: 9px;\nwidth: 15px;\n}<\/p>\n<p>  .veeva-2024 .arrow-link span.icon {\nheight: 9px;\nwidth: 15px;\n}\n<\/style>\n<p><main class=\"veeva-2024\"><\/p>\n<div id=\"\">\n<section id=\"hero\" class=\"hero-centered hero-centered--image\" style=\"padding:160px 0 70px 0\">\n<div class=\"container copy-container copy-container--center\">\n<h1>A Pr\u00f3xima Gera\u00e7\u00e3o da Su\u00edte CRM<\/h1>\n<p>Veeva AI Integrada <br \/>Vendas, Marketing e \u00c1rea M\u00e9dica Conectadas<\/p>\n<div class=\"copy-container__buttons\">\n            <a class=\"button-primary button-primary--gradient\" href=\"\/products\/crm-suite\/crm\/#ai-in-vault-crm\">Veja a IA no Vault CRM<\/a>\n        <\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"alert-news alert-news--compact\">\n    <a class=\"alert-news__wrapper container\" href=\"https:\/\/www.veeva.com\/br\/resources\/mais-de-125-clientes-do-vault-crm-impulsionam-a-transformacao\/\" target=\"_self\" rel=\"noopener\"><\/p>\n<div class=\"alert-news__inner\">\n<div class=\"alert-news__copy\">\n<h6>Mais de 125 clientes ativos no Vault CRM em todo o mundo<\/h6>\n<\/p><\/div>\n<p>            <span class=\"alert-news__btn-desktop button-secondary\"><\/p>\n<div class=\"button-icon button-icon--white\"><\/div>\n<p>             <\/span>\n        <\/div>\n<p>    <\/a><br \/>\n<\/section>\n<section class=\"marquee-subpoints marquee-subpoints--light marquee-subpoints--3-up\" style=\"margin-top:55px;margin-bottom:0\">\n<div class=\"copy-container container copy-container--center copy-container--eyebrow-gradient\" style=\"margin-bottom:0\">\n<h3>Vault CRM Suite<\/h3>\n<p>\nA su\u00edte Vault CRM integra as principais aplica\u00e7\u00f5es e processos comerciais para um planejamento de campo e engajamento mais eficaz atrav\u00e9s de canais pessoais e digitais.<\/p>\n<div class=\"copy-container__buttons\" style=\"margin-top:0px\">\n<p><a style=\"font-size: 16px;text-decoration:underline;white-space:nowrap\" class=\"button-secondary button-secondary--black\" href=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2023\/07\/Veeva-Product-Sheet-CRM-Suite.pdf?\" target=\"_blank\" rel=\"noopener\"><br \/>\n    <img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/svg\/icons\/btn-download--black.svg\" alt=\"\"> <span>Acesse o Product Sheet<br \/>\n<\/span><\/a>\n\t\t<\/div>\n<\/p><\/div>\n<\/section>\n<p><!-- Z Pattern - Products, Light --><\/p>\n<section class=\"z-pattern z-pattern-products z-pattern--light  section-rounded-top\" style=\"background: white;margin-top:80px;margin-bottom:90px;\">\n<div class=\"z-pattern__wrapper container\">\n<div class=\"z-pattern__inner\">\n            <!-- z-pattern: copy container --><\/p>\n<div class=\"copy-container copy-container--center copy-container--left-lg\">\n<h3>Omnichannel CRM<\/h3>\n<p>\n              O Vault CRM \u00e9 uma solu\u00e7\u00e3o robusta para a ind\u00fastria farmac\u00eautica que integra dados e software, unificando vendas, marketing e \u00e1rea m\u00e9dica em uma \u00fanica plataforma.  <\/p>\n<p>\nEle re\u00fane funcionalidades essenciais como o gerenciamento de dados cadastrais, compartilhamento e gest\u00e3o de conte\u00fado, planejamento de territ\u00f3rio, gest\u00e3o de contas estrat\u00e9gicas (KAM), controle de amostras, call center, vendas internas al\u00e9m de ferramentas para engajamento presencial e remoto. <\/p>\n<p class=\"arrow-link d-none\"><a href=\"https:\/\/www.veeva.com\/products\/crm-suite\/crm\/\">See Vault CRM in Action<\/a> <span class=\"icon\" data-icon=\"arrow-right-1\"><\/span>    <\/p>\n<style>\n.veeva-2024 .z-pattern-products__subpoint-headline:before {\nbackground: none;\ncontent: \"\";\nheight: 100%;\nleft: 0;\nposition: absolute;\ntop: 0;\nwidth: 2px;\n}\n@media (min-width:991px) {\n.veeva-2024 .z-pattern-products__subpoint-headline:before {\nbackground: linear-gradient(180deg,#f7981d,#ff6b00);\ncontent: \"\";\nheight: 100%;\nleft: 0;\nposition: absolute;\ntop: 0;\nwidth: 2px;\n}\n}\n.veeva-2024 .z-pattern--light .z-pattern-products__subpoint-headline.top-product h6 {\nmargin-bottom:0;flex-grow:0;text-align:center;margin:auto;\n}\n@media (min-width:991px) {\n.veeva-2024 .z-pattern--light .z-pattern-products__subpoint-headline.top-product h6 {\ntext-align:left;margin:unset;\n}\n}\n.veeva-2024 .copy-container .z-pattern-products__subpoint-body {\ncolor:unset;font-size:14px;\n}\n.veeva-2024 .copy-container .z-pattern-products__subpoint-body.top-item p {\ntext-align:center;\n}\n@media (min-width:991px) {\n.veeva-2024 .copy-container .z-pattern-products__subpoint-body.top-item p {\ntext-align:left;\n}\n}\n@media (min-width:768px) {\n.veeva-2024 .copy-container .z-pattern-products__subpoint-body.top-item p {\ncolor:unset;font-size:16px;\n}\n}\n<\/style>\n<p><a href=\"\/br\/products\/crm-suite\/crm\/\" style=\"margin-top:20px;\" class=\"z-pattern-products__subpoint\" href=\"\" rel=\"noopener\"><\/p>\n<div class=\"z-pattern-products__subpoint-headline top-product\">\n<h6 >Veeva AI para Vault CRM<br \/>\n<span class=\"icon\" data-icon=\"arrow-up-right--black\"><\/span><\/h6>\n<\/p><\/div>\n<div class=\"z-pattern-products__subpoint-body top-item\" style=\"text-align:left\">\n<p>Agentes espec\u00edficos para a ind\u00fastria integrados ao Vault CRM para aumentar a produtividade. Os agentes iniciais incluem: Agente de M\u00eddia, Agente de Pr\u00e9-visita, Agente de Monitoramento de Texto e Agente de Voz.\n<\/p>\n<\/p><\/div>\n<p> <\/a>                   <\/p><\/div>\n<p>            <!-- z-pattern: img section --><\/p>\n<div class=\"z-pattern__image\">\n<div class=\"z-pattern__image-wrapper\">\n                    <img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/12\/product-detail-hero-veeva-ai-for-vault-crm@2x.png\" alt=\"\" \/>\n                <\/div>\n<\/p><\/div>\n<p>            <!-- z-pattern: content section --><\/p>\n<div class=\"z-pattern__content z-pattern__subgrid\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"z-pattern__wrapper products container\">\n<div class=\"z-pattern__inner\">\n<p>            <!-- z-pattern: content section --><\/p>\n<div class=\"z-pattern__content z-pattern__subgrid\">\n<p>                 <a class=\"z-pattern-products__subpoint\" href=\"\/br\/products\/crm-suite\/events-management\/\" rel=\"noopener\"><\/p>\n<div class=\"z-pattern-products__subpoint-headline\">\n<h6>Events Management<\/h6>\n<p>                        <span class=\"icon\" data-icon=\"arrow-up-right--black\"><\/span>\n                    <\/div>\n<div class=\"z-pattern-products__subpoint-body\">\n<p>Uma aplica\u00e7\u00e3o para gerenciar o ciclo de vida completo de eventos e informa\u00e7\u00f5es relacionadas, incluindo conte\u00fado, participantes, palestrantes e despesas.\n<\/p>\n<\/p><\/div>\n<p>                <\/a><br \/>\n                <a class=\"z-pattern-products__subpoint\" href=\"\/br\/products\/crm-suite\/campaign-manager\/\" rel=\"noopener\"><\/p>\n<div class=\"z-pattern-products__subpoint-headline\">\n<h6>Campaign Manager<\/h6>\n<p>                        <span class=\"icon\" data-icon=\"arrow-up-right--black\"><\/span>\n                    <\/div>\n<div class=\"z-pattern-products__subpoint-body\">\n<p>Uma aplica\u00e7\u00e3o para profissionais de marketing da ind\u00fastria farmac\u00eautica coordenarem o engajamento de vendas e marketing em campanhas unificadas, utilizando canais digitais e de campo.\n<\/p>\n<\/p><\/div>\n<p>                <\/a><\/p>\n<p>                <a class=\"z-pattern-products__subpoint\" href=\"\/br\/products\/crm-suite\/align\/\"  rel=\"noopener\"><\/p>\n<div class=\"z-pattern-products__subpoint-headline\">\n<h6>Align<\/h6>\n<p>                        <span class=\"icon\" data-icon=\"arrow-up-right--black\"><\/span>\n                    <\/div>\n<div class=\"z-pattern-products__subpoint-body\">\n<p>Uma aplica\u00e7\u00e3o de planejamento estrat\u00e9gico voltada \u00e0 gest\u00e3o da estrutura comercial, alinhamento de territ\u00f3rios e planos de ciclo, incluindo a valida\u00e7\u00e3o das equipes de campo integrada ao Vault CRM.<\/p>\n<\/p><\/div>\n<p>                <\/a><\/p>\n<p>                <a target=\"blank\" class=\"z-pattern-products__subpoint\" href=\"\/products\/crm-suite\/patient-crm\/\" rel=\"noopener\"><\/p>\n<div class=\"z-pattern-products__subpoint-headline\">\n<h6>Patient CRM<\/h6>\n<p>                        <span class=\"icon\" data-icon=\"arrow-up-right--black\"><\/span>\n                    <\/div>\n<div class=\"z-pattern-products__subpoint-body\">\n<p>Uma aplica\u00e7\u00e3o para gerenciar programas de suporte ao paciente e  de dados pessoais sens\u00edveis  (PHI\/PII) na plataforma Vault. (No momento, dispon\u00edvel apenas para o mercado norte americano).\n<\/p>\n<\/p><\/div>\n<p>                <\/a><\/p>\n<p>                <a target=\"blank\" class=\"z-pattern-products__subpoint\" href=\"\/products\/crm-suite\/territory-designer\/\" rel=\"noopener\"><\/p>\n<div class=\"z-pattern-products__subpoint-headline\">\n<h6>Territory Designer<\/h6>\n<p>                        <span class=\"icon\" data-icon=\"arrow-up-right--black\"><\/span>\n                    <\/div>\n<div class=\"z-pattern-products__subpoint-body\">\n<p>Uma aplica\u00e7\u00e3o utilizada para desenhar territ\u00f3rios geogr\u00e1ficos otimizados para equipes m\u00e9dicas e de for\u00e7a de vendas.\n<\/p>\n<\/p><\/div>\n<p>                <\/a><\/p>\n<p>                <a target=\"blank\" class=\"z-pattern-products__subpoint\" href=\"\/products\/crm-suite\/network-mdm\/\" rel=\"noopener\"><\/p>\n<div class=\"z-pattern-products__subpoint-headline\">\n<h6>Network MDM<\/h6>\n<p>                        <span class=\"icon\" data-icon=\"arrow-up-right--black\"><\/span>\n                    <\/div>\n<div class=\"z-pattern-products__subpoint-body\">\n<p>Uma plataforma global de gest\u00e3o de dados mestres (MDM) e  governan\u00e7a de dados de clientes, projetada para empresas farmac\u00eauticas e biotecnol\u00f3gicas globais.<\/p>\n<\/p><\/div>\n<p>                <\/a><\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"border-box\">\n<div class=\"copy-container container copy-container--center copy-container--eyebrow-gradient\">\n<h6>Melhores Juntos<\/h6>\n<h4 style=\"margin-bottom:10px;margin-top:10px;\">Software Conectado e Dados Conectados<\/h4>\n<div style=\"margin-bottom:40px;\"class=\"copy-container__buttons\">\n\t\t  <a class=\"button-outline button-outline--black\" href=\"\/resources\/find-and-better-engage-the-right-hcps-with-connected-data-and-software\/\" target=\"_self\" rel=\"noopener\">Veja em a\u00e7\u00e3o<\/a>\n\t\t<\/div>\n<\/p><\/div>\n<p><\/p>\n<div class=\"listed-up__cards container\">\n<div class=\"impact-card impact-card-linkout\">\n\t\t\t\t<a href=\"https:\/\/www.veeva.com\/products\/opendata\/\">\t\t\t<\/p>\n<h6 style=\"margin-bottom:3px\">OpenData<\/h6>\n<p style=\"margin-bottom:15px;color:black\">Dados de Mercado<\/p>\n<p>Accurate and comprehensive customer reference data <span class=\"icon\" data-icon=\"arrow-right-1\"><\/span><\/p>\n<p>\t\t\t\t<\/a>\n\t\t\t<\/div>\n<div class=\"impact-card impact-card-linkout\">\n\t\t\t\t<a href=\"https:\/\/www.veeva.com\/products\/veeva-link\/overview\/\">\t\t\t<\/p>\n<h6 style=\"margin-bottom:3px\">Link<\/h6>\n<p style=\"margin-bottom:15px;color:black\">Dados e Insights<\/p>\n<p>Aprofunde relacionamentos, acelere insights e otimize processos com a su\u00edte Link<br \/>\n<span class=\"icon\" data-icon=\"arrow-right-1\"><\/span><\/p>\n<p>\t\t\t\t<\/a>\n\t\t\t<\/div>\n<div class=\"impact-card impact-card-linkout\">\n\t\t\t\t<a href=\"https:\/\/www.veeva.com\/products\/hcpaccess\/\">\t\t\t<\/p>\n<h6 style=\"margin-bottom:3px\">HCP Access<\/h6>\n<p style=\"margin-bottom:15px;color:black\">M\u00e9tricas de Acesso ao Profissional da Sa\u00fade<\/p>\n<p>M\u00e9tricas de acesso a HCPs que podem ser utilizadas para melhorar a segmenta\u00e7\u00e3o, o direcionamento e o planejamento de engajamento <span class=\"icon\" data-icon=\"arrow-right-1\"><\/span><\/p>\n<p>\t\t\t\t<\/a>\n\t\t\t<\/div>\n<p>\t\t\t<!-- [] -->\n\t\t  <\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"d-none listed-up listed-up-accent listed-up--light listed-up-accent--card-center section-rounded-top\" style=\"background: linear-gradient(0deg,#fff 5.2%,#eef1f5 92.04%);padding-top:80px;margin-top:60px;padding-bottom:40px;margin-bottom:0\">\n<div class=\"copy-container--eyebrow-gradient copy-container--center\">\n<h3 style=\"margin-bottom:40px;;margin-top:10px;\">The Future of Customer Engagement<\/h3>\n<\/p><\/div>\n<div class=\"listed-up__cards container\">\n<div class=\"listed-up-card\" href=\"#\" target=\"_self\">\n<div class=\"bar\"><\/div>\n<h5>Seamless Collaboration<\/h5>\n<p>Connect sales, marketing, and medical teams to break down silos and coordinate engagement.<\/p>\n<\/p><\/div>\n<div class=\"listed-up-card\" href=\"#\" target=\"_self\">\n<div class=\"bar\"><\/div>\n<h5>Customer Centricity<\/h5>\n<p>A single customer view across teams for more personalized interactions and a better customer experience.<\/p>\n<\/p><\/div>\n<div class=\"listed-up-card\" href=\"#\" target=\"_self\">\n<div class=\"bar\"><\/div>\n<h5>More Effective Field<\/h5>\n<p>Embedded AI and actionable data deliver deeper insights, faster decision making, and increased productivity.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n<div id=\"gateway\">\n<div class=\"blended-bg\" style=\"padding-top:0\">\n<p><!-- Quote - Tabs, Dark, Logo Tablist --><\/p>\n<section class=\"quote-tabs quote-tabs--dark\">\n<div class=\"container\">\n<div class=\"copy-container copy-container--center copy-container--eyebrow-gradient\" style=\"margin-bottom:60px\">\n<h6>Parceira de Confian\u00e7a da Ind\u00fastria de Life Sciences<\/h6>\n<h3>L\u00edderes Escolhem a Su\u00edte Vault CRM<\/h3>\n<\/p><\/div>\n<\/p><\/div>\n<p>    <!-- content --><\/p>\n<div class=\"quote-tabs__content\">\n<div class=\"container\">\n<div class=\"carousel slide carousel-fade\" data-slide-interval=\"8500\">\n<div class=\"carousel-indicators\"><\/div>\n<div class=\"carousel-inner\">\n<!-- slide 0 --><\/p>\n<div class=\"carousel-item\">\n<div class=\"quote-card quote-card-full quote-card-full quote-card-full--medium-text\">\n<div class=\"row main-quote-row\">\n<div class=\"col-lg-8 quote-content\">\n<p style=\"text-indent: -.32em;\">&#8220;O <span style=\"color:#F5670E\">Vault CRM<\/span> ajudar\u00e1 a fornecer \u00e0 Novo Nordisk a base tecnol\u00f3gica para impulsionar a execu\u00e7\u00e3o comercial.&#8221;<\/p>\n<h5>Emil Kongsh\u00f8j Larsen<\/h5>\n<h6>Vice-presidente Executivo, Opera\u00e7\u00f5es Internacionais<br \/>\n\t\t\t\t\t\t\t\t\t<br \/>Novo Nordisk<\/h6>\n<p>\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"75\" src=\"\/wp-content\/uploads\/2025\/08\/crm-suite-logo-novo-nordisk-120x85@2x.png\" alt=\"\" \/>\n                          \t\t<\/div>\n<div class=\"col-lg-4\" style=\"text-align:center\">\n                          \t\t\t<a href=\"\/resources\/novo-nordisk-international-operations-commits-to-veeva-vault-crm\/ \"><img decoding=\"async\" class=\"headshot\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2026\/01\/quote-carousel-headshot-emil-kongshoj-447x410@2x.png\"><\/a>\n\t\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><!-- slide 1 --><\/p>\n<div class=\"carousel-item\">\n<div class=\"quote-card quote-card-full quote-card-full quote-card-full--medium-text\">\n<div class=\"row main-quote-row\">\n<div class=\"col-lg-8 quote-content\">\n<p style=\"text-indent: -.32em;\">&#8220;Ao<span style=\"color:#F5670E\"> incorporar a IA em cada etapa da jornada do cliente <\/span> \u2014 desde a forma como os profissionais de sa\u00fade recebem informa\u00e7\u00f5es cient\u00edficas relevantes sobre o nosso portf\u00f3lio at\u00e9 como interagem com a nossa for\u00e7a de campo \u2014  o Veeva AIsurge como a solu\u00e7\u00e3o ideal para nos apoiar em nossa miss\u00e3o de fornecer medicamentos que transformam vidas a pacientes em todo o mundo.&#8221;<\/p>\n<h5>Greg Meyers<\/h5>\n<h6>Vice-presidente Executivo, Diretor de Tecnologia e Digital (Chief Digital and Technology Officer)<br \/>\n\t\t\t\t\t\t\t\t<br \/>Bristol Myers Squibb<\/h6>\n<p>\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"225\" src=\"\/wp-content\/uploads\/2025\/09\/quote-logo-bristol-myers-squibb-1.png\" alt=\"\" \/>\n                          \t\t<\/div>\n<div class=\"col-lg-4\" style=\"text-align:center\">\n                          \t\t\t<a href=\"\/resources\/bristol-myers-squibb-commits-to-veeva-vault-crm\/\"><img decoding=\"async\" class=\"headshot\" src=\"\/wp-content\/uploads\/2025\/09\/greg-meyers-carousel-1.png\"><\/a>\n\t\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><!-- slide 2 --><\/p>\n<div class=\"carousel-item\">\n<div class=\"quote-card quote-card-full quote-card-full quote-card-full--medium-text\">\n<div class=\"row main-quote-row\">\n<div class=\"col-lg-8 quote-content\">\n<p style=\"text-indent: -.32em;\">&#8220;<span style=\"color:#F5670E\">A proposta de IA integrada <\/span> e o suporte de uma equipe de confian\u00e7a trouxeram total seguran\u00e7a para a transi\u00e7\u00e3o ao Vault CRM, um sistema que realmente viabiliza o nosso futuro.\u201d<\/p>\n<h5> Debbie Young<\/h5>\n<h6>Diretora de Estrat\u00e9gia Multicanal e Insights de Clientes<br \/>\n\t\t\t\t\t\t\t\t<br \/>Otsuka Europe<\/h6>\n<p>\t\t\t\t\t\t\t\t<img decoding=\"async\" clas=\"hidden\" width=\"225\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2023\/11\/otsuka-150-70.png\" alt=\"\" \/>\n                          \t\t<\/div>\n<div class=\"col-lg-4\" style=\"text-align:center\">\n                          \t\t\t<a href=\"\/customer-stories\/agentic-transformation-bayer-otsuka-on-next-gen-vault-crm\/\"><img decoding=\"async\" class=\"headshot\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/12\/crm-product-quote-debbie-young-otsuka-447x410@2x.png\"><\/a>\n\t\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><!-- slide 3 --><\/p>\n<div class=\"carousel-item\">\n<div class=\"quote-card quote-card-full quote-card-full quote-card-full--medium-text\">\n<div class=\"row main-quote-row\">\n<div class=\"col-lg-8 quote-content\">\n<p style=\"text-indent: -.32em;\">&#8220;Estamos entusiasmados em usar o <span style=\"color:#F5670E\">Agente de Monitoramento de Texto do Veeva AI<\/span>   (Veeva AI Text Monitoring Agent Agent) como parte de nossa estrat\u00e9gia para desenvolver recursos de IA em nossos neg\u00f3cios. O Veeva AI nos proporciona uma vis\u00e3o mais estrat\u00e9gica dos clientes garantindo um engajamento mais eficaz na \u00e1rea de doen\u00e7as raras.\u201d<\/p>\n<h5>Kea Lingo<\/h5>\n<h6>Diretora de Informa\u00e7\u00e3o (Chief Information Officer)<br \/>\n\t\t\t\t\t\t\t\t<br \/>Crinetics<\/h6>\n<p>\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"hidden\" width=\"225\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/12\/kea-lingo-carousel@2x.png \" alt=\"\" \/>\n                          \t\t<\/div>\n<div class=\"col-lg-4\" style=\"text-align:center\">\n                          \t\t\t<a href=\"https:\/\/www.veeva.com\/resources\/veeva-ai-agents-now-available-to-increase-productivity-and-customer-centricity\/\"><img decoding=\"async\" class=\"headshot\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/12\/kea-lingo-carousel@2x.png\"><\/a>\n\t\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p> <!-- slide 4 --><\/p>\n<div class=\"carousel-item\">\n<div class=\"quote-card quote-card-full quote-card-full quote-card-full--medium-text\">\n<div class=\"row main-quote-row\">\n<div class=\"col-lg-8 quote-content\">\n<p style=\"text-indent: -.32em;\">\u201cCom <span style=\"color:#F5670E\">dados e IA em sua ess\u00eancia<\/span>, Vault o Vault CRM nos ajudar\u00e1 a criar<span style=\"color:#F5670E\">intera\u00e7\u00f5es mais personalizadas<\/span>, dando \u00e0s nossas equipes os <span style=\"color:#F5670E\">insights<\/span> necess\u00e1rios para elevar o suporte aos profissionais de sa\u00fade e otimizar o cuidado aos pacientes.\u201d<\/p>\n<h6>Diretora de Tecnologia e Digital (Chief Digital and Technology Officer)<br \/>\n\t\t\t\t\t\t\t\t<br \/>Roche<\/h6>\n<\/p><\/div>\n<div class=\"col-lg-4\" style=\"text-align:center\">\n                          \t\t\t<a href=\"\/resources\/veeva-announces-expanded-partnership-with-roche\/\"><img decoding=\"async\" class=\"headshot\" src=\"\/wp-content\/uploads\/2025\/11\/wafaa-mamilli-carousel.png\"><\/a>\n\t\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p><!-- slide 5 --><\/p>\n<div class=\"carousel-item\">\n<div class=\"quote-card quote-card-full quote-card-full quote-card-full--medium-text\">\n<div class=\"row main-quote-row\">\n<div class=\"col-lg-8 quote-content\">\n<p style=\"text-indent: -.32em;\">\u201cEstamos nos mantendo \u00e0 frente da <span style=\"color:#F5670E\">curva de inova\u00e7\u00e3o<\/span>. O Campaign Manager \u00e9 uma das muitas inova\u00e7\u00f5es que <span style=\"color:#F5670E\">elevar\u00e3o a forma como nos engajamos com os HCPs [Profissionais de Sa\u00fade]<\/span>.\u201d\n<\/p>\n<h5>Baptiste Omont<\/h5>\n<h6>Diretor S\u00eanior, Sistemas Comerciais e M\u00e9dicos<br \/>\n\t\t\t\t\t\t\t\t<br \/>Idorsia<\/h6>\n<p>\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"125\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/11\/idorsia-logo-155x50-1.png\" alt=\"\" \/>\n                          \t\t<\/div>\n<div class=\"col-lg-4\" style=\"text-align:center\">\n                          \t\t\t<a href=\"\/customer-stories\/vault-crm-momentum-100-customers-drive-transformation\/\"><img decoding=\"async\" class=\"headshot\" src=\"\/wp-content\/uploads\/2025\/11\/baptiste-omont-carousel@2x.png\"><\/a>\n\t\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>                    <!-- slide 5 --><\/p>\n<div class=\"carousel-item\">\n<div class=\"quote-card quote-card-full quote-card-full quote-card-full--medium-text\">\n<div class=\"row main-quote-row\">\n<div class=\"col-lg-8 quote-content\">\n<p style=\"text-indent: -.32em;\">&#8220;Nossa ideia era criar uma <span style=\"color:#F5670E\">plataforma de insights para o cliente<\/span>, e o Vault CRM \u00e9 a base para isso. Agora \u00e9 a hora de enriquec\u00ea-la com informa\u00e7\u00f5es mais poderosas, com <span style=\"color:#F5670E\">ferramentas mais poderosas, como agentes de IA.&#8221;<\/span><\/p>\n<h5>Alexander Alex<\/h5>\n<h6>Head da Plataforma Veeva<br \/>\n\t\t\t\t\t\t\t\t\t<br \/>Bayer<\/h6>\n<p>\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"75\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/05\/quote-logo-bayer.png\" alt=\"\" \/>\n                          \t\t<\/div>\n<div class=\"col-lg-4\" style=\"text-align:center\">\n                          \t\t\t<a href=\"\/customer-stories\/bayers-vault-crm-go-live\/\"><img decoding=\"async\" class=\"headshot\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/10\/alex-alexander-carousel-1.png\"><\/a>\n\t\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n<p><!-- Logo Wall - Listed &#x2705; --><\/p>\n<section style=\"padding-top:0px\" class=\"logo-wall-listed logo-wall-listed--dark logo-wall-listed--floating-logos\">\n<div class=\"logo-wall-listed__logos container\">\n\t\t<img decoding=\"async\" alt=\"\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/04\/bayer.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/04\/biontech.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/04\/boehringeringelheim.png\"><br \/>\n                <img decoding=\"async\" alt=\"\" src=\"\/wp-content\/uploads\/2026\/02\/vault-crm-logo-wall-crinetics-white_250x100-Color-WhiteBG@2x.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"Gilead\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/06\/Product-Page-Customer-Logo-Gilead-White-TransparentBG@2x.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/04\/gsk.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/09\/Product-Page-Customer-Logo-Immedica-Pharma-white@2x.png\"><br \/>\n<img decoding=\"async\" alt=\"\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/04\/immunitybio.png\"><br \/>\n<img decoding=\"async\" alt=\"Merck\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/06\/Product-Page-Customer-Logo-Merck-White-TransparentBG@2x-1.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"neurocrine\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/04\/neurocrine.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"NewAmsterdam\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/09\/Product-Page-Customer-Logo-NewAmsterdam-Pharma-white@2x.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"novonordisk\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/04\/novonordisk.png\"><\/p>\n<p><img decoding=\"async\" alt=\"Otsuka\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/06\/Product-Page-Customer-Logo-Otsuka-White-TransparentBG@2x-1.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"PMV\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/09\/Product-Page-Customer-Logo-PMV-white@2x.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"replimune\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/11\/product-page-customer-logo-replimune-white-transparentBG@2x.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"Revolution\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/09\/Product-Page-Customer-Logo-Revolution-Medicines-white@2x.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"shionogi\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/04\/shionogi.png\"><br \/>\n\t\t<img decoding=\"async\" alt=\"sobi\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/04\/sobi.png\">\n\t<\/div>\n<\/section><\/div>\n<\/div>\n<section class=\"resource-block-featured resource-block-featured--light section-contained-width--xl\" id=\"resource-block-0\">\n<div class=\"container\">\n<div style=\"margin-bottom:60px\" class=\"copy-container copy-container--center copy-container--eyebrow-gradient\">\n<h6>Vault CRM Suite<\/h6>\n<h3>Veja as Novidades<\/h3>\n<\/p><\/div>\n<div class=\"resource-block__cards resource-block__cards--featured resource-block__cards--featured--6\">\n\t\t\t<a id=\"resource-card--summit\" class=\"resource-card resource-card--with-bg-gradient-orange\" href=\"https:\/\/www.veeva.com\/br\/products\/veeva-ai\/\"><\/p>\n<div class=\"resource-card__text\">\n<h5>Agentes de IA j\u00e1 Dispon\u00edveis <\/h5>\n<div class=\"d-none d-lg-block button-secondary button-secondary--black\" href=\"#\" target=\"_self\">\n    \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/svg\/icons\/btn-arrow-up-right--black.svg\" alt=\"\" \/>\n\t\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"resource-card__media resource-card__media--bg\" style=\"background-image: url('https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/05\/veeva-ai-callout-bg.png'); background-position: bottom right;\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/05\/veeva-ai-callout-product-3.png\" alt=\"Veeva AI\">\n\t\t\t\t<\/div>\n<p>\t\t  \t<\/a><\/p>\n<p><a class=\"resource-card\" href=\"\/resources\/agentic-ai-in-vault-crm\/\"><\/p>\n<div class=\"resource-card__text\">\n<h5>Veja o Veeva AI para Vault CRM<\/h5>\n<div class=\"d-none d-lg-block button-secondary button-secondary--black\" href=\"#\" target=\"_self\">\n    \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/svg\/icons\/btn-arrow-up-right--black.svg\" alt=\"\" \/>\n\t\t\t\t\t<\/div>\n<\/p><\/div>\n<p>\t\t  \t<\/a><\/p>\n<p><a class=\"resource-card\" href=\"\/resources\/veeva-and-biomarin-form-long-term-strategic-partnership\/\"><\/p>\n<div class=\"resource-card__text\">\n<h5>Veeva e BioMarin Estabelecem Parceria Estrat\u00e9gica de Longo Prazo<br \/>\n<\/h5>\n<div class=\"d-none d-lg-block button-secondary button-secondary--black\" href=\"#\" target=\"_self\">\n    \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/svg\/icons\/btn-arrow-up-right--black.svg\" alt=\"\" \/>\n\t\t\t\t\t<\/div>\n<\/p><\/div>\n<p>\t\t  \t<\/a>\t\t<\/p>\n<p>\t<a class=\"resource-card\" href=\"\/resources\/novo-nordisk-international-operations-commits-to-veeva-vault-crm\/ \"><\/p>\n<div class=\"resource-card__text\">\n<h5>A Novo Nordisk potencializa suas opera\u00e7\u00f5es globais atrav\u00e9s de um CRM de \u00faltima gera\u00e7\u00e3o e do uso de IA ag\u00eantica <\/p>\n<\/h5>\n<div class=\"d-none d-lg-block button-secondary button-secondary--black\" href=\"#\" target=\"_self\">\n    \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/svg\/icons\/btn-arrow-up-right--black.svg\" alt=\"\" \/>\n\t\t\t\t\t<\/div>\n<\/p><\/div>\n<p>\t\t  \t<\/a><\/p>\n<p>\t\t  \t<a class=\"resource-card\" href=\"https:\/\/www.veeva.com\/br\/resources\/mais-de-125-clientes-do-vault-crm-impulsionam-a-transformacao\/\"><\/p>\n<div class=\"resource-card__text\">\n<h5>Veja por que mais de 125 clientes escolheram o Vault CRM para impulsionar a inova\u00e7\u00e3o e a transforma\u00e7\u00e3o<br \/>\n<\/h5>\n<div class=\"d-none d-lg-block button-secondary button-secondary--black\" href=\"#\" target=\"_self\">\n    \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/svg\/icons\/btn-arrow-up-right--black.svg\" alt=\"\" \/>\n\t\t\t\t\t<\/div>\n<\/p><\/div>\n<p>\t\t  \t<\/a><br \/>\n<a class=\"resource-card\" href=\"\/customer-stories\/agentic-transformation-bayer-otsuka-on-next-gen-vault-crm\/\"><\/p>\n<div class=\"resource-card__text\">\n<h5>Transforma\u00e7\u00e3o ag\u00eantica: Bayer AG e Otsuka Europe no Vault CRM de \u00faltima gera\u00e7\u00e3o<\/h5>\n<div class=\"d-none d-lg-block button-secondary button-secondary--black\" href=\"#\" target=\"_self\">\n    \t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/svg\/icons\/btn-arrow-up-right--black.svg\" alt=\"\" \/><\/p><\/div>\n<\/p><\/div>\n<p>\t\t  \t<\/a>\n\t\t<\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"hero-contained hero-contained--gradient hero-contained--footer-fix\">\n<div class=\"copy-container container copy-container--center\">\n<h3>Impulsione Engajamentos Mais Impactantes com os Clientes<\/h3>\n<div class=\"copy-container__buttons\">\n          \t<a class=\"button-primary button-primary--gradient\" href=\"\/br\/contact-us\/\">Entre em Contato<\/a>\n    \t<\/div>\n<\/p><\/div>\n<\/section>\n<\/div>\n<p><\/main><\/p>\n","protected":false},"excerpt":{"rendered":"<p>One conversation. All channels. Engage in relevant, timely conversations informed by a complete customer view.<\/p>\n","protected":false},"author":334,"featured_media":0,"parent":20394,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/veeva-2024.full-page.php","meta":{"footnotes":""},"class_list":["post-62064","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"A Pr\u00f3xima Gera\u00e7\u00e3o da Su\u00edte CRM Veeva AI Integrada Vendas, Marketing e \u00c1rea M\u00e9dica Conectadas Veja a IA no Vault CRM Mais de 125 clientes ativos no Vault CRM em todo o mundo Vault CRM Suite A su\u00edte Vault CRM integra as principais aplica\u00e7\u00f5es e processos comerciais para um planejamento de campo e engajamento mais\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/pantheon.veeva.com\/br\/products\/crm-suite\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Veeva -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Veeva Vault CRM Suite - Veeva\" \/>\n\t\t<meta property=\"og:description\" content=\"A Pr\u00f3xima Gera\u00e7\u00e3o da Su\u00edte CRM Veeva AI Integrada Vendas, Marketing e \u00c1rea M\u00e9dica Conectadas Veja a IA no Vault CRM Mais de 125 clientes ativos no Vault CRM em todo o mundo Vault CRM Suite A su\u00edte Vault CRM integra as principais aplica\u00e7\u00f5es e processos comerciais para um planejamento de campo e engajamento mais\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/pantheon.veeva.com\/br\/products\/crm-suite\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-05-12T17:54:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-09-01T18:22:29+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Veeva Vault CRM Suite - Veeva\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A Pr\u00f3xima Gera\u00e7\u00e3o da Su\u00edte CRM Veeva AI Integrada Vendas, Marketing e \u00c1rea M\u00e9dica Conectadas Veja a IA no Vault CRM Mais de 125 clientes ativos no Vault CRM em todo o mundo Vault CRM Suite A su\u00edte Vault CRM integra as principais aplica\u00e7\u00f5es e processos comerciais para um planejamento de campo e engajamento mais\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/products\\\/crm-suite\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/products\\\/#listItem\",\"name\":\"Products\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/products\\\/#listItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/products\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/products\\\/crm-suite\\\/#listItem\",\"name\":\"Veeva Vault CRM Suite\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/products\\\/crm-suite\\\/#listItem\",\"position\":3,\"name\":\"Veeva Vault CRM Suite\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/products\\\/#listItem\",\"name\":\"Products\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/#organization\",\"name\":\"Veeva\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/products\\\/crm-suite\\\/#webpage\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/products\\\/crm-suite\\\/\",\"name\":\"Veeva Vault CRM Suite - Veeva\",\"description\":\"A Pr\\u00f3xima Gera\\u00e7\\u00e3o da Su\\u00edte CRM Veeva AI Integrada Vendas, Marketing e \\u00c1rea M\\u00e9dica Conectadas Veja a IA no Vault CRM Mais de 125 clientes ativos no Vault CRM em todo o mundo Vault CRM Suite A su\\u00edte Vault CRM integra as principais aplica\\u00e7\\u00f5es e processos comerciais para um planejamento de campo e engajamento mais\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/products\\\/crm-suite\\\/#breadcrumblist\"},\"datePublished\":\"2026-05-12T14:54:56-03:00\",\"dateModified\":\"2026-09-01T15:22:29-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/\",\"name\":\"Veeva\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Veeva Vault CRM Suite - Veeva<\/title>\n\n","aioseo_head_json":{"title":"Veeva Vault CRM Suite - Veeva","description":"A Pr\u00f3xima Gera\u00e7\u00e3o da Su\u00edte CRM Veeva AI Integrada Vendas, Marketing e \u00c1rea M\u00e9dica Conectadas Veja a IA no Vault CRM Mais de 125 clientes ativos no Vault CRM em todo o mundo Vault CRM Suite A su\u00edte Vault CRM integra as principais aplica\u00e7\u00f5es e processos comerciais para um planejamento de campo e engajamento mais","canonical_url":"https:\/\/pantheon.veeva.com\/br\/products\/crm-suite\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/pantheon.veeva.com\/br\/products\/crm-suite\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/br#listItem","position":1,"name":"Home","item":"https:\/\/pantheon.veeva.com\/br","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/br\/products\/#listItem","name":"Products"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/br\/products\/#listItem","position":2,"name":"Products","item":"https:\/\/pantheon.veeva.com\/br\/products\/","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/br\/products\/crm-suite\/#listItem","name":"Veeva Vault CRM Suite"},"previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/br#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/br\/products\/crm-suite\/#listItem","position":3,"name":"Veeva Vault CRM Suite","previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/br\/products\/#listItem","name":"Products"}}]},{"@type":"Organization","@id":"https:\/\/pantheon.veeva.com\/br\/#organization","name":"Veeva","url":"https:\/\/pantheon.veeva.com\/br\/"},{"@type":"WebPage","@id":"https:\/\/pantheon.veeva.com\/br\/products\/crm-suite\/#webpage","url":"https:\/\/pantheon.veeva.com\/br\/products\/crm-suite\/","name":"Veeva Vault CRM Suite - Veeva","description":"A Pr\u00f3xima Gera\u00e7\u00e3o da Su\u00edte CRM Veeva AI Integrada Vendas, Marketing e \u00c1rea M\u00e9dica Conectadas Veja a IA no Vault CRM Mais de 125 clientes ativos no Vault CRM em todo o mundo Vault CRM Suite A su\u00edte Vault CRM integra as principais aplica\u00e7\u00f5es e processos comerciais para um planejamento de campo e engajamento mais","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/pantheon.veeva.com\/br\/#website"},"breadcrumb":{"@id":"https:\/\/pantheon.veeva.com\/br\/products\/crm-suite\/#breadcrumblist"},"datePublished":"2026-05-12T14:54:56-03:00","dateModified":"2026-09-01T15:22:29-03:00"},{"@type":"WebSite","@id":"https:\/\/pantheon.veeva.com\/br\/#website","url":"https:\/\/pantheon.veeva.com\/br\/","name":"Veeva","inLanguage":"en-US","publisher":{"@id":"https:\/\/pantheon.veeva.com\/br\/#organization"}}]},"og:locale":"en_US","og:site_name":"Veeva -","og:type":"article","og:title":"Veeva Vault CRM Suite - Veeva","og:description":"A Pr\u00f3xima Gera\u00e7\u00e3o da Su\u00edte CRM Veeva AI Integrada Vendas, Marketing e \u00c1rea M\u00e9dica Conectadas Veja a IA no Vault CRM Mais de 125 clientes ativos no Vault CRM em todo o mundo Vault CRM Suite A su\u00edte Vault CRM integra as principais aplica\u00e7\u00f5es e processos comerciais para um planejamento de campo e engajamento mais","og:url":"https:\/\/pantheon.veeva.com\/br\/products\/crm-suite\/","article:published_time":"2026-05-12T17:54:56+00:00","article:modified_time":"2026-09-01T18:22:29+00:00","twitter:card":"summary_large_image","twitter:title":"Veeva Vault CRM Suite - Veeva","twitter:description":"A Pr\u00f3xima Gera\u00e7\u00e3o da Su\u00edte CRM Veeva AI Integrada Vendas, Marketing e \u00c1rea M\u00e9dica Conectadas Veja a IA no Vault CRM Mais de 125 clientes ativos no Vault CRM em todo o mundo Vault CRM Suite A su\u00edte Vault CRM integra as principais aplica\u00e7\u00f5es e processos comerciais para um planejamento de campo e engajamento mais"},"aioseo_meta_data":{"post_id":"62064","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2026-04-20 12:48:20","updated":"2026-09-01 18:47:21","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"breadcrumb_settings":null,"seo_analyzer_scan_date":"2026-09-01 18:22:30"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/br\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/br\/products\/\" title=\"Products\">Products<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tVeeva Vault CRM Suite\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/pantheon.veeva.com\/br"},{"label":"Products","link":"https:\/\/pantheon.veeva.com\/br\/products\/"},{"label":"Veeva Vault CRM Suite","link":"https:\/\/pantheon.veeva.com\/br\/products\/crm-suite\/"}],"_links":{"self":[{"href":"https:\/\/pantheon.veeva.com\/br\/wp-json\/wp\/v2\/pages\/62064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pantheon.veeva.com\/br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pantheon.veeva.com\/br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pantheon.veeva.com\/br\/wp-json\/wp\/v2\/users\/334"}],"replies":[{"embeddable":true,"href":"https:\/\/pantheon.veeva.com\/br\/wp-json\/wp\/v2\/comments?post=62064"}],"version-history":[{"count":38,"href":"https:\/\/pantheon.veeva.com\/br\/wp-json\/wp\/v2\/pages\/62064\/revisions"}],"predecessor-version":[{"id":63082,"href":"https:\/\/pantheon.veeva.com\/br\/wp-json\/wp\/v2\/pages\/62064\/revisions\/63082"}],"up":[{"embeddable":true,"href":"https:\/\/pantheon.veeva.com\/br\/wp-json\/wp\/v2\/pages\/20394"}],"wp:attachment":[{"href":"https:\/\/pantheon.veeva.com\/br\/wp-json\/wp\/v2\/media?parent=62064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}