{"id":54884,"date":"2020-12-09T18:06:03","date_gmt":"2020-12-09T17:06:03","guid":{"rendered":"http:\/\/www.veeva.com\/eu\/?post_type=resources_de&#038;p=54884"},"modified":"2026-04-09T16:01:49","modified_gmt":"2026-04-09T14:01:49","slug":"roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen","status":"publish","type":"resources_de","link":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/","title":{"rendered":"Roche entscheidet sich f\u00fcr <br> Veeva\u2019s Development Cloud Anwendungen"},"content":{"rendered":"<p align=\"center\"><em>F\u00fchrendes Pharmaunternehmen entscheidet sich f\u00fcr Veeva Vault-Anwendungen <br \/> in den Bereichen Klinik, Regulierung und Qualit\u00e4t<\/em><\/p>\n<p><strong>BARCELONA, Spanien \u2013 12. Okt. 2020 \u2013<\/strong> <a href=\"\/eu\/\" target=\"_blank\" rel=\"noopener noreferrer\">Veeva Systems<\/a> (NYSE: VEEV) gab heute bekannt, dass Roche (SWX: ROG) sich auf globaler Ebene f\u00fcr Veeva\u2019s <a href=\"\/eu\/products\/development-cloud\/\" target=\"_blank\" rel=\"noopener noreferrer\">Development Cloud<\/a>-Anwendungen entschieden hat, um seine  klinischen, regulatorischen und qualit\u00e4tsrelevanten Gesch\u00e4ftsprozesse zu rationalisieren. Das Unternehmen wechselt damit zu vereinheitlichten Anwendungen durch Veeva\u2019s <a href=\"\/eu\/products\/veeva-clinical-platform\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault Clinical<\/a>, <a href=\"\/eu\/products\/veeva-rim\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault RIM<\/a> und <a href=\"\/eu\/products\/quality-cloud\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault Quality Suite<\/a>. Hierdurch steigert Roche \u00fcber  den gesamten Produktlebenszyklus hinweg seine Effizienz, verbessert die Datenqualit\u00e4t und stellt die Compliance sicher.<\/p>\n<p>\u201eDie Beschleunigung der Arzneimittelentwicklung und der Produktversorgung sind eine strategische Priorit\u00e4t f\u00fcr innovative Life-Science-Unternehmen wie Roche\u201c, sagt Rik Van Mol, Vizepr\u00e4sident von Veeva zust\u00e4ndig f\u00fcr Development Cloud Strategy. \u201eDie Veeva Development Cloud bricht System- und Prozess-Silos auf, so dass Life Science-Unternehmen innovative Behandlungen schneller an seine Patienten liefern k\u00f6nnen.\u201c<\/p>\n<p>Roche standardisiert die klinischen Anwendungen <a href=\"\/eu\/products\/veeva-etmf\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault eTMF<\/a> und <a href=\"\/eu\/products\/veeva-ctms\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault CTMS<\/a>, die regulatorischen Anwendungen <a href=\"\/eu\/products\/veeva-submissions\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault Submissions<\/a>, <a href=\"\/eu\/products\/veeva-registrations\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault Registrations<\/a> und <a href=\"\/eu\/products\/veeva-submissions-archive\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault Submissions Archive<\/a> sowie die Qualit\u00e4tsanwendungen <a href=\"\/eu\/products\/veeva-qms\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault QMS<\/a> und <a href=\"\/eu\/products\/veeva-qualitydocs\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vault QualityDocs<\/a>.<\/p>\n<p>Erfahren Sie mehr \u00fcber die Veeva Vault Development Cloud auf dem bevorstehenden <a href=\"\/events\/rd-summit\/\" target=\"_blank\" rel=\"noopener noreferrer\">Veeva R&#038;D and Quality Summit<\/a> vom 13. bis 14. Oktober 2020. Diese Online-Veranstaltung steht Fachleuten der Life Sciences Industrie offen. Registrieren Sie sich und bleiben Sie \u00fcber Programmdetails auf <a href=\"\/events\/rd-summit\/\" target=\"_blank\" rel=\"noopener noreferrer\">veeva.com\/Summit<\/a> auf dem Laufenden.<\/p>\n<p><strong>Zus\u00e4tzliche Informationen<\/strong><br \/>\nEntdecken Sie Veeva auf LinkedIn: <a href=\"https:\/\/www.linkedin.com\/company\/veeva-systems\" target=\"_blank\" rel=\"noopener noreferrer\">linkedin.com\/company\/veeva-systems<\/a><br \/>\nFolgen Sie @Veeva_EU auf Twitter: <a href=\"https:\/\/www.twitter.com\/\/Veeva_EU\" target=\"_blank\" rel=\"noopener noreferrer\">twitter.com\/Veeva_EU<\/a><br \/>\nLiken Sie Veeva auf Facebook: <a href=\"https:\/\/www.facebook.com\/VeevaSystems\" target=\"_blank\" rel=\"noopener noreferrer\">facebook.com\/veevasystems<\/a><\/p>\n<p><strong>\u00dcber Veeva Systems<\/strong><br \/>\nVeeva Systems Inc. ist ein f\u00fchrender Anbieter von Cloud-L\u00f6sungen \u2013 unter Einbeziehung von Daten, Software und Dienstleistungen \u2013 f\u00fcr die globale Life Sciences-Branche. Veeva hat sich der Innovation, h\u00f6chster Produktqualit\u00e4t und dem Kundenerfolg verpflichtet. Das Unternehmen betreut mehr als 900 Kunden, von den gr\u00f6\u00dften Pharmakonzernen der Welt bis hin zu neu gegr\u00fcndeten Biotechfirmen. Das Unternehmen hat seinen Hauptsitz in der San Francisco Bay Area und verf\u00fcgt \u00fcber Niederlassungen in ganz Nordamerika, Europa, Asien und Lateinamerika. Weitere Informationen erhalten Sie unter <a href=\"\/eu\/de\/\">veeva.com\/eu\/de<\/a>.<\/p>\n<p><strong>Zukunftsgerichtete Aussagen<\/strong><br \/>\nDiese Pressemitteilung enth\u00e4lt zukunftsgerichtete Aussagen, so etwa zur Marktnachfrage und zur Akzeptanz der Produkte und Dienstleistungen von Veeva, zu den Ergebnissen aus der Nutzung von Produkten und Dienstleistungen von Veeva und zu allgemeinen Gesch\u00e4ftsbedingungen (einschlie\u00dflich zu denen durch die fortlaufenden Auswirkungen durch COVID-19), insbesondere in der Life-Sciences-Branche. Alle in dieser Pressemitteilung enthaltenen zukunftsgerichteten Aussagen beruhen auf vergangenen Gesch\u00e4ftsleistungen von Veeva und den aktuellen Pl\u00e4nen, Sch\u00e4tzungen und Erwartungen des Unternehmens und stellen keine Zusicherung dar, dass diese Pl\u00e4ne, Sch\u00e4tzungen oder Erwartungen erreicht werden. Diese zukunftsgerichteten Aussagen stellen die Erwartungen von Veeva zum Zeitpunkt dieser Pressemitteilung dar. Sp\u00e4tere Ereignisse k\u00f6nnten dazu f\u00fchren, dass diese Erwartungen sich \u00e4ndern, und Veeva lehnt jegliche Verpflichtung zu einer Aktualisierung der zukunftsgerichteten Aussagen in der Zukunft ab. Diese zukunftsgerichteten Aussagen unterliegen bekannten und unbekannten Risiken und Unsicherheiten, die dazu f\u00fchren k\u00f6nnen, dass die tats\u00e4chlichen Ergebnisse wesentlich davon abweichen. Zus\u00e4tzliche Risiken und Unsicherheiten, die sich auf die Finanzergebnisse von Veeva auswirken k\u00f6nnten, sind unter den \u00dcberschriften \u201eRisk Factors\u201c und \u201eManagement\u2019s Discussion and Analysis of Financial Condition and Results of Operations\u201c in der Einreichung des Unternehmens auf Formular 10-Q f\u00fcr den Zeitraum bis zum 31. Juli 2020 enthalten. Diese ist auf der Website des Unternehmens unter <a href=\"\/\" target=\"_blank\" rel=\"noopener noreferrer\">veeva.com<\/a> im Bereich f\u00fcr Investoren und auf der Website der SEC unter <a href=\"https:\/\/www.sec.gov\/\" target=\"_blank\" rel=\"noopener noreferrer\">sec.gov<\/a> verf\u00fcgbar. Weitere Informationen zu potenziellen Risiken, die sich auf die tats\u00e4chlichen Ergebnisse auswirken k\u00f6nnten, werden in anderen Einreichungen enthalten sein, die Veeva gelegentlich bei der SEC vorlegt.<\/p>\n<p>###<\/p>\n<p><strong>Kontakt:<\/strong><br \/>\nVeeva Systems<br \/>\n<a href=\"mailto:pr@veeva.com\">pr@veeva.com<\/a><\/p>\n<p>Deivis Mercado<br \/>\nVeeva Systems<br \/>\n925-226-8821<br \/>\n<a href=\"mailto:deivis.mercado@veeva.com\">deivis.mercado@veeva.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roche optimiert seine R&#038;D Gesch\u00e4ftsprozesse mit Hilfe von Veeva\u2019s Vault Clinical-, RIM- und Quality-Suiten.<\/p>\n","protected":false},"featured_media":53701,"parent":0,"template":"","class_list":["post-54884","resources_de","type-resources_de","status-publish","has-post-thumbnail","hentry","resources-de-canonical-unique","resource-html-content-yes","resource-de-type-pressemitteilungen","resource-de-area-area-development-cloud","resource-de-product-product-development-cloud"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Roche optimiert seine R&amp;D Gesch\u00e4ftsprozesse mit Hilfe von Veeva\u2019s Vault Clinical-, RIM- und Quality-Suiten.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Roche entscheidet sich f\u00fcr Veeva\u2019s Development Cloud Anwendungen | Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:description\" content=\"Roche optimiert seine R&amp;D Gesch\u00e4ftsprozesse mit Hilfe von Veeva\u2019s Vault Clinical-, RIM- und Quality-Suiten.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/pantheon.veeva.com\/eu\/wp-content\/uploads\/2020\/12\/Roche-Press-Release_DE_v1_FB-LinkedIn.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/pantheon.veeva.com\/eu\/wp-content\/uploads\/2020\/12\/Roche-Press-Release_DE_v1_FB-LinkedIn.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-12-09T17:06:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-09T14:01:49+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Roche entscheidet sich f\u00fcr Veeva\u2019s Development Cloud Anwendungen | Veeva Systems Europe\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Roche optimiert seine R&amp;D Gesch\u00e4ftsprozesse mit Hilfe von Veeva\u2019s Vault Clinical-, RIM- und Quality-Suiten.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2026\/08\/web-default-featured-image-1200x630-2@2x.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/#listItem\",\"name\":\"Resources - DE\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/#listItem\",\"position\":2,\"name\":\"Resources - DE\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/#listItem\",\"name\":\"Make Unique\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/#listItem\",\"position\":3,\"name\":\"Make Unique\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\\\/#listItem\",\"name\":\"Roche entscheidet sich f\\u00fcr  Veeva\\u2019s Development Cloud Anwendungen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/#listItem\",\"name\":\"Resources - DE\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\\\/#listItem\",\"position\":4,\"name\":\"Roche entscheidet sich f\\u00fcr  Veeva\\u2019s Development Cloud Anwendungen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/#listItem\",\"name\":\"Make Unique\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/#organization\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\\\/#webpage\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\\\/\",\"name\":\"Roche entscheidet sich f\\u00fcr Veeva\\u2019s Development Cloud Anwendungen | Veeva Systems Europe\",\"description\":\"Roche optimiert seine R&D Gesch\\u00e4ftsprozesse mit Hilfe von Veeva\\u2019s Vault Clinical-, RIM- und Quality-Suiten.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Roche-Selects-Veeva-Development-Cloud-Applications.png\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\\\/#mainImage\",\"width\":340,\"height\":240,\"caption\":\"Roche Selects Veeva Development Cloud Applications\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\\\/#mainImage\"},\"datePublished\":\"2020-12-09T18:06:03+01:00\",\"dateModified\":\"2026-04-09T16:01:49+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Roche entscheidet sich f\u00fcr Veeva\u2019s Development Cloud Anwendungen | Veeva Systems Europe<\/title>\n\n","aioseo_head_json":{"title":"Roche entscheidet sich f\u00fcr Veeva\u2019s Development Cloud Anwendungen | Veeva Systems Europe","description":"Roche optimiert seine R&D Gesch\u00e4ftsprozesse mit Hilfe von Veeva\u2019s Vault Clinical-, RIM- und Quality-Suiten.","canonical_url":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu#listItem","position":1,"name":"Home","item":"https:\/\/pantheon.veeva.com\/eu","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/#listItem","name":"Resources - DE"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/#listItem","position":2,"name":"Resources - DE","item":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/resources-de-canonical\/unique\/#listItem","name":"Make Unique"},"previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/resources-de-canonical\/unique\/#listItem","position":3,"name":"Make Unique","item":"https:\/\/pantheon.veeva.com\/eu\/resources-de-canonical\/unique\/","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/#listItem","name":"Roche entscheidet sich f\u00fcr  Veeva\u2019s Development Cloud Anwendungen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/#listItem","name":"Resources - DE"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/#listItem","position":4,"name":"Roche entscheidet sich f\u00fcr  Veeva\u2019s Development Cloud Anwendungen","previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/resources-de-canonical\/unique\/#listItem","name":"Make Unique"}}]},{"@type":"Organization","@id":"https:\/\/pantheon.veeva.com\/eu\/#organization","name":"Veeva Systems Europe","description":"EU Site","url":"https:\/\/pantheon.veeva.com\/eu\/"},{"@type":"WebPage","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/#webpage","url":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/","name":"Roche entscheidet sich f\u00fcr Veeva\u2019s Development Cloud Anwendungen | Veeva Systems Europe","description":"Roche optimiert seine R&D Gesch\u00e4ftsprozesse mit Hilfe von Veeva\u2019s Vault Clinical-, RIM- und Quality-Suiten.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/pantheon.veeva.com\/eu\/#website"},"breadcrumb":{"@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/pantheon.veeva.com\/eu\/wp-content\/uploads\/2020\/10\/Roche-Selects-Veeva-Development-Cloud-Applications.png","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/#mainImage","width":340,"height":240,"caption":"Roche Selects Veeva Development Cloud Applications"},"primaryImageOfPage":{"@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/#mainImage"},"datePublished":"2020-12-09T18:06:03+01:00","dateModified":"2026-04-09T16:01:49+02:00"},{"@type":"WebSite","@id":"https:\/\/pantheon.veeva.com\/eu\/#website","url":"https:\/\/pantheon.veeva.com\/eu\/","name":"Veeva Systems Europe","description":"EU Site","inLanguage":"en-US","publisher":{"@id":"https:\/\/pantheon.veeva.com\/eu\/#organization"}}]},"og:locale":"en_US","og:site_name":"Veeva Systems Europe","og:type":"article","og:title":"Roche entscheidet sich f\u00fcr Veeva\u2019s Development Cloud Anwendungen | Veeva Systems Europe","og:description":"Roche optimiert seine R&amp;D Gesch\u00e4ftsprozesse mit Hilfe von Veeva\u2019s Vault Clinical-, RIM- und Quality-Suiten.","og:url":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/","og:image":"https:\/\/pantheon.veeva.com\/eu\/wp-content\/uploads\/2020\/12\/Roche-Press-Release_DE_v1_FB-LinkedIn.png","og:image:secure_url":"https:\/\/pantheon.veeva.com\/eu\/wp-content\/uploads\/2020\/12\/Roche-Press-Release_DE_v1_FB-LinkedIn.png","og:image:width":1200,"og:image:height":628,"article:published_time":"2020-12-09T17:06:03+00:00","article:modified_time":"2026-04-09T14:01:49+00:00","twitter:card":"summary_large_image","twitter:title":"Roche entscheidet sich f\u00fcr Veeva\u2019s Development Cloud Anwendungen | Veeva Systems Europe","twitter:description":"Roche optimiert seine R&amp;D Gesch\u00e4ftsprozesse mit Hilfe von Veeva\u2019s Vault Clinical-, RIM- und Quality-Suiten.","twitter:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2026\/08\/web-default-featured-image-1200x630-2@2x.jpg"},"aioseo_meta_data":{"post_id":"54884","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"article","og_image_type":"custom_image","og_image_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2020\/12\/Roche-Press-Release_DE_v1_FB-LinkedIn.png","og_image_width":"1200","og_image_height":"628","og_image_custom_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2020\/12\/Roche-Press-Release_DE_v1_FB-LinkedIn.png","og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"summary_large_image","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2021-08-24 15:57:29","updated":"2026-08-24 20:56:11","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":"2026-08-24 20:56:11"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/eu\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/\" title=\"Resources - DE\">Resources - DE<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/eu\/resources-de-canonical\/unique\/\" title=\"Make Unique\">Make Unique<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tRoche entscheidet sich f\u00fcr <br> Veeva\u2019s Development Cloud Anwendungen\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/pantheon.veeva.com\/eu"},{"label":"Resources - DE","link":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/"},{"label":"Make Unique","link":"https:\/\/pantheon.veeva.com\/eu\/resources-de-canonical\/unique\/"},{"label":"Roche entscheidet sich f\u00fcr <br> Veeva\u2019s Development Cloud Anwendungen","link":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/roche-entscheidet-sich-fur-veevas-development-cloud-anwendungen\/"}],"_links":{"self":[{"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de\/54884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de"}],"about":[{"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/types\/resources_de"}],"version-history":[{"count":1,"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de\/54884\/revisions"}],"predecessor-version":[{"id":54889,"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de\/54884\/revisions\/54889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/media\/53701"}],"wp:attachment":[{"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/media?parent=54884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}