{"id":72395,"date":"2023-07-12T13:03:39","date_gmt":"2023-07-12T11:03:39","guid":{"rendered":"https:\/\/www.veeva.com\/eu\/?post_type=resources_de&#038;p=72395"},"modified":"2026-04-27T17:18:22","modified_gmt":"2026-04-27T15:18:22","slug":"merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren","status":"publish","type":"resources_de","link":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/","title":{"rendered":"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\u00e4ufe weltweit zu optimieren"},"content":{"rendered":"<p align=\"center\"><em>Veeva Vault MedInquiry rationalisiert das End-to-End-Anfragemanagement in gro\u00dfem Umfang<\/em><\/p>\n<p><strong>BARCELONA, Spanien \u2014 12 Juli 2023<\/strong> &#8211; <a href=\"\/eu\/\">Veeva Systems<\/a> gab heute bekannt, dass Merck KGaA, Darmstadt, Deutschland, <a href=\"\/eu\/products\/vault-medical\/veeva-medinquiry\/\" target=\"_blank\" rel=\"noopener noreferrer\">Veeva Vault MedInquiry<\/a> als globales medizinisches Informationsmanagementsystem einsetzt. Das f\u00fchrende Biopharmaunternehmen nutzt Veeva Vault MedInquiry f\u00fcr die effektive Verwaltung globaler medizinischer Informationsanfragen und unterst\u00fctzt seine Teams weltweit bei der Rationalisierung funktions\u00fcbergreifender Gesch\u00e4ftsprozesse f\u00fcr einen besseren wissenschaftlichen Austausch.<\/p>\n<p>&#8220;Mit Veeva Vault MedInquiry steht unseren Anwendern ein cloudbasiertes System nach Industriestandard zur Verf\u00fcgung, das sowohl die Leistung als auch die Benutzerfreundlichkeit verbessert und unsere Kommunikation mit den Kunden st\u00e4rkt&#8221;, so Priya Bhasin, Scientific Director, Global Medical Information bei Merck KGaA, Darmstadt, Deutschland.<\/p>\n<p>Mit Vault MedInquiry verf\u00fcgt die Merck KGaA, Darmstadt, Deutschland, nun \u00fcber einen einheitlichen globalen Rahmen f\u00fcr das medizinische Informationsmanagement. Dank den Verbindungen zwischen Aufnahmekan\u00e4len, Sicherheits-, Qualit\u00e4ts-, Inhalts- und CRM-Systemen k\u00f6nnen die Teams weiterhin die Einhaltung der regionalen und lokalen Anforderungen der L\u00e4nder, die sie beliefern, sicherstellen.<\/p>\n<p>&#8220;Unsere enge Zusammenarbeit mit Veeva war ausschlaggebend, um eine vollst\u00e4ndig integrierte Umgebung zu gew\u00e4hrleisten und schnelle Innovationen zu erm\u00f6glichen, damit unsere globalen Teams schneller hervorragende Dienstleistungen erbringen k\u00f6nnen&#8221;, sagte Stacey Eggert, Senior Director, Global Medical Information bei Merck KGaA, Darmstadt, Deutschland.<\/p>\n<p>&#8220;Die enge Partnerschaft zwischen Merck KGaA, Darmstadt, Deutschland und Veeva wird die globalen medizinischen Informationsabl\u00e4ufe mit Veeva Vault MedInquiry modernisieren und sich in die Prozesslandschaft des Unternehmens einf\u00fcgen, um die weltweite Einheitlichkeit zu f\u00f6rdern&#8221;, sagte Callum Hawes, Senior Director, Medical Inquiry Strategy bei Veeva. &#8220;Unsere Teams haben mehrere Integrationsstr\u00f6me parallel gemanagt und eng zusammengearbeitet, um das neue System auf die globalen Anforderungen der Merck KGaA, Darmstadt, zuzuschneiden, mit der M\u00f6glichkeit, von neuen Innovationen zu profitieren und sich f\u00fcr zuk\u00fcnftiges Wachstum anzupassen.&#8221; <\/p>\n<p>Vault MedInquiry bietet eine vollst\u00e4ndige, skalierbare L\u00f6sung, die den gesamten Prozess der Verwaltung medizinischer Anfragen von der Annahme bis zur Bearbeitung steuert.<\/p>\n<p><strong>Weitere Informationen<\/strong><br \/>\nF\u00fcr mehr Informationen zu Veeva Vault MedInquiry besuchen Sie: <a href=\"\/eu\/products\/vault-medical\/veeva-medinquiry\/\" target=\"_blank\" rel=\"noopener noreferrer\">veeva.com\/eu\/VaultMedInquiry<\/a><br \/>\nVeeva auf LinkedIn: <a href=\"https:\/\/www.linkedin.com\/company\/veeva-systems\/\" target=\"_blank\" rel=\"noopener noreferrer\">linkedin.com\/company\/veeva-systems<\/a>\n<\/p>\n<p><strong>Informationen zu Veeva Systems<\/strong><br \/>\nVeeva ist der weltweit f\u00fchrende Anbieter von Cloud-Software f\u00fcr die Biowissenschaftsindustrie. Veeva ist bestrebt, Innovation, Produktexzellenz und Kundenerfolg zu f\u00f6rdern. Das Unternehmen bedient \u00fcber 1.000 Kunden, darunter sowohl die gr\u00f6\u00dften Biopharma-Unternehmen der Welt als auch aufstrebende Biotechnologieunternehmen. Als <a href=\"\/pbc\/\" target=\"_blank\" rel=\"noopener noreferrer\">gemeinn\u00fctzige Gesellschaft<\/a> ist Veeva bestrebt, die Interessen aller Interessengruppen, einschlie\u00dflich Kunden, Mitarbeiter, Aktion\u00e4re und der von ihm bedienten Branchen, in Einklang zu bringen. Weitere Informationen finden Sie unter <a href=\"\/eu\/de\/\">veeva.com\/eu\/de<\/a>.\n<\/p>\n<p><strong>Veeva zukunftsgerichtete Aussagen<\/strong><br \/>\nDiese Ver\u00f6ffentlichung enth\u00e4lt zukunftsgerichtete Aussagen \u00fcber die Produkte und Dienstleistungen von Veeva sowie die erwarteten Ergebnisse oder Vorteile bei der Nutzung unserer Produkte und Dienstleistungen. Diese Aussagen beruhen auf unseren derzeitigen Erwartungen. Die tats\u00e4chlichen Ergebnisse k\u00f6nnten wesentlich von den in dieser Ver\u00f6ffentlichung dargelegten abweichen, und wir sind nicht verpflichtet, solche Aussagen zu aktualisieren. Es gibt zahlreiche Risiken, die das Potenzial haben, sich negativ auf unsere Ergebnisse auszuwirken. Diese Risiken und Unsicherheiten sind in unserem Formular 10-Q f\u00fcr den Zeitraum bis zum 30. April 2023 dargelegt, das Sie <a href=\"https:\/\/www.sec.gov\/ix?doc=\/Archives\/edgar\/data\/0001393052\/000139305223000034\/veev-20230430.htm#i8fa5054a533a40eb9ed853f24032d7d7_124\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a> finden k\u00f6nnen (eine Zusammenfassung der Risiken, die sich auf unser Gesch\u00e4ft auswirken k\u00f6nnten, finden Sie auf den Seiten 37 und 38), sowie in unseren nachfolgenden Einreichungen bei der SEC, die Sie unter <a href=\"https:\/\/www.sec.gov\/\" target=\"_blank\" rel=\"noopener noreferrer\">sec.gov<\/a> abrufen k\u00f6nnen.\n<\/p>\n<p class=\"text-center\">\n###\n<\/p>\n<p>\n<strong>Kontakt:<\/strong>\t<\/p>\n<p>Jeremy Whittaker<br \/>\t<br \/>\nVeeva Systems<br \/>\t<br \/>\n+49-695-095-5486<br \/>\t<br \/>\n<a href=\"mailto:jeremy.whittaker@veeva.com\">jeremy.whittaker@veeva.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veeva Vault MedInquiry rationalisiert das End-to-End-Anfragemanagement in gro\u00dfem Umfang.<\/p>\n","protected":false},"featured_media":71953,"parent":0,"template":"","class_list":["post-72395","resources_de","type-resources_de","status-publish","has-post-thumbnail","hentry","resources-de-canonical-unique","resource-html-content-yes","resource-de-type-pressemitteilungen","resource-de-area-medizin","resource-de-product-medinquiry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Veeva Vault MedInquiry rationalisiert das End-to-End-Anfragemanagement in gro\u00dfem Umfang.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\u00e4ufe weltweit zu optimieren | Veeva Systems Europe\" \/>\n\t\t<meta property=\"og:description\" content=\"Veeva Vault MedInquiry rationalisiert das End-to-End-Anfragemanagement in gro\u00dfem Umfang.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/08\/Merck-KGaA-Press-Release_Social_1200x630-1_DE-1.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/08\/Merck-KGaA-Press-Release_Social_1200x630-1_DE-1.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-07-12T11:03:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-27T15:18:22+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\u00e4ufe weltweit zu optimieren | Veeva Systems Europe\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Veeva Vault MedInquiry rationalisiert das End-to-End-Anfragemanagement in gro\u00dfem Umfang.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/08\/Merck-KGaA-Press-Release_Social_1200x630-1_DE-1.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/#listItem\",\"name\":\"Resources - DE\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/#listItem\",\"position\":2,\"name\":\"Resources - DE\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/#listItem\",\"name\":\"Make Unique\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/#listItem\",\"position\":3,\"name\":\"Make Unique\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\\\/#listItem\",\"name\":\"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\\u00e4ufe weltweit zu optimieren\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/#listItem\",\"name\":\"Resources - DE\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\\\/#listItem\",\"position\":4,\"name\":\"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\\u00e4ufe weltweit zu optimieren\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/resources-de-canonical\\\/unique\\\/#listItem\",\"name\":\"Make Unique\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/#organization\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\\\/#webpage\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\\\/\",\"name\":\"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\\u00e4ufe weltweit zu optimieren | Veeva Systems Europe\",\"description\":\"Veeva Vault MedInquiry rationalisiert das End-to-End-Anfragemanagement in gro\\u00dfem Umfang.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/3Q22_Pulseinsights_340x240_Thumb_PulseData.png\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\\\/#mainImage\",\"width\":340,\"height\":240},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/de\\\/ressourcen\\\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\\\/#mainImage\"},\"datePublished\":\"2023-07-12T13:03:39+02:00\",\"dateModified\":\"2026-04-27T17:18:22+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/\",\"name\":\"Veeva Systems Europe\",\"description\":\"EU Site\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/eu\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\u00e4ufe weltweit zu optimieren | Veeva Systems Europe<\/title>\n\n","aioseo_head_json":{"title":"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\u00e4ufe weltweit zu optimieren | Veeva Systems Europe","description":"Veeva Vault MedInquiry rationalisiert das End-to-End-Anfragemanagement in gro\u00dfem Umfang.","canonical_url":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu#listItem","position":1,"name":"Home","item":"https:\/\/pantheon.veeva.com\/eu","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/#listItem","name":"Resources - DE"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/#listItem","position":2,"name":"Resources - DE","item":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/resources-de-canonical\/unique\/#listItem","name":"Make Unique"},"previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/resources-de-canonical\/unique\/#listItem","position":3,"name":"Make Unique","item":"https:\/\/pantheon.veeva.com\/eu\/resources-de-canonical\/unique\/","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/#listItem","name":"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\u00e4ufe weltweit zu optimieren"},"previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/#listItem","name":"Resources - DE"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/#listItem","position":4,"name":"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\u00e4ufe weltweit zu optimieren","previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/eu\/resources-de-canonical\/unique\/#listItem","name":"Make Unique"}}]},{"@type":"Organization","@id":"https:\/\/pantheon.veeva.com\/eu\/#organization","name":"Veeva Systems Europe","description":"EU Site","url":"https:\/\/pantheon.veeva.com\/eu\/"},{"@type":"WebPage","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/#webpage","url":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/","name":"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\u00e4ufe weltweit zu optimieren | Veeva Systems Europe","description":"Veeva Vault MedInquiry rationalisiert das End-to-End-Anfragemanagement in gro\u00dfem Umfang.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/pantheon.veeva.com\/eu\/#website"},"breadcrumb":{"@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/pantheon.veeva.com\/eu\/wp-content\/uploads\/2023\/07\/3Q22_Pulseinsights_340x240_Thumb_PulseData.png","@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/#mainImage","width":340,"height":240},"primaryImageOfPage":{"@id":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/#mainImage"},"datePublished":"2023-07-12T13:03:39+02:00","dateModified":"2026-04-27T17:18:22+02:00"},{"@type":"WebSite","@id":"https:\/\/pantheon.veeva.com\/eu\/#website","url":"https:\/\/pantheon.veeva.com\/eu\/","name":"Veeva Systems Europe","description":"EU Site","inLanguage":"en-US","publisher":{"@id":"https:\/\/pantheon.veeva.com\/eu\/#organization"}}]},"og:locale":"en_US","og:site_name":"Veeva Systems Europe","og:type":"article","og:title":"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\u00e4ufe weltweit zu optimieren | Veeva Systems Europe","og:description":"Veeva Vault MedInquiry rationalisiert das End-to-End-Anfragemanagement in gro\u00dfem Umfang.","og:url":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/","og:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/08\/Merck-KGaA-Press-Release_Social_1200x630-1_DE-1.png","og:image:secure_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/08\/Merck-KGaA-Press-Release_Social_1200x630-1_DE-1.png","article:published_time":"2023-07-12T11:03:39+00:00","article:modified_time":"2026-04-27T15:18:22+00:00","twitter:card":"summary_large_image","twitter:title":"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\u00e4ufe weltweit zu optimieren | Veeva Systems Europe","twitter:description":"Veeva Vault MedInquiry rationalisiert das End-to-End-Anfragemanagement in gro\u00dfem Umfang.","twitter:image":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/08\/Merck-KGaA-Press-Release_Social_1200x630-1_DE-1.png"},"aioseo_meta_data":{"post_id":"72395","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"custom_image","og_image_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/08\/Merck-KGaA-Press-Release_Social_1200x630-1_DE-1.png","og_image_width":"1200","og_image_height":"630","og_image_custom_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/08\/Merck-KGaA-Press-Release_Social_1200x630-1_DE-1.png","og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"summary_large_image","twitter_image_type":"custom_image","twitter_image_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/08\/Merck-KGaA-Press-Release_Social_1200x630-1_DE-1.png","twitter_image_custom_url":"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2023\/08\/Merck-KGaA-Press-Release_Social_1200x630-1_DE-1.png","twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2023-08-01 15:44:31","updated":"2026-08-24 20:58:19","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":"2026-08-24 20:58:19"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/eu\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/\" title=\"Resources - DE\">Resources - DE<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/eu\/resources-de-canonical\/unique\/\" title=\"Make Unique\">Make Unique<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tMerck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\u00e4ufe weltweit zu optimieren\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/pantheon.veeva.com\/eu"},{"label":"Resources - DE","link":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/"},{"label":"Make Unique","link":"https:\/\/pantheon.veeva.com\/eu\/resources-de-canonical\/unique\/"},{"label":"Merck KGaA, Darmstadt, Deutschland, partnert mit Veeva, um medizinische Informationsabl\u00e4ufe weltweit zu optimieren","link":"https:\/\/pantheon.veeva.com\/eu\/de\/ressourcen\/merck-kgaa-darmstadt-deutschland-partnert-mit-veeva-um-medizinische-informationsablaufe-weltweit-zu-optimieren\/"}],"_links":{"self":[{"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de\/72395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de"}],"about":[{"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/types\/resources_de"}],"version-history":[{"count":1,"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de\/72395\/revisions"}],"predecessor-version":[{"id":72409,"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/resources_de\/72395\/revisions\/72409"}],"wp:attachment":[{"href":"https:\/\/pantheon.veeva.com\/eu\/wp-json\/wp\/v2\/media?parent=72395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}