{"id":21058,"date":"2015-10-20T16:48:00","date_gmt":"2015-10-20T20:48:00","guid":{"rendered":"http:\/\/www.veeva.com\/?page_id=21058"},"modified":"2026-07-30T12:03:54","modified_gmt":"2026-07-30T03:03:54","slug":"ip","status":"publish","type":"page","link":"https:\/\/pantheon.veeva.com\/jp\/ip\/","title":{"rendered":"\u77e5\u7684\u8ca1\u7523"},"content":{"rendered":"<h2>Veeva\u306e\u5546\u6a19<\/h2>\n<ul>\n<li><img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/05\/cda-logo-orange-128x56@2x.png\" alt=\"\" height=\"20\" style=\"border-radius: 0 !important;\"><\/li>\n<li>COMMON DATA ARCHITECTURE FOR LIFE SCIENCES<\/li>\n<\/ul>\n<h2>Veeva\u767b\u9332\u306e\u5546\u6a19<\/h2>\n<ul>\n<li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2015\/10\/iplogo2.png\" alt=\"iplogo2\" width=\"82\" height=\"20\" style=\"border-radius: 0 !important;\"> <\/li>\n<li><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2015\/10\/Veeva.png\" alt=\"iplogo1\" width=\"82\" height=\"30\" style=\"border-radius: 0 !important;\"><\/li>\n<li><img decoding=\"async\" src=\"https:\/\/www.veeva.com\/eu\/wp-content\/uploads\/2017\/02\/Veeva-icon.png\" alt=\"\" height=\"20\" style=\"border-radius: 0 !important;\"><\/li>\n<li><img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2023\/09\/crossix.png\" alt=\"\" height=\"20\" style=\"border-radius: 0 !important;\"><\/li>\n<li> CROSSIX <\/li>\n<li> ORGWIKI<\/li>\n<li> QUALITYONE<\/li>\n<li> SITEVAULT<\/li>\n<li> VAULT<\/li>\n<li> VEEVA<\/li>\n<li>IREP<\/li>\n<\/ul>\n<h2>\u7c73\u56fd\u7279\u8a31\uff1a<\/h2>\n<p>Veeva \u306e Commercial Cloud \u30a2\u30d7\u30ea\u30b1\u30fc\u30b7\u30e7\u30f3\uff08Veeva CRM\u3001Veeva Approved Email\u3001Events\u3001Engage\u3001Veeva CLM\u3001Veeva CRM MyInsights\u306a\u3069\uff09\u3001Vault\u3001Vault Clinical\u3001Veeva RIM\u3001Veeva Safety\u3001Veeva CDMS\u3001Crossix \u3092\u542b\u3080\u5f53\u793e\u306e\u30d7\u30e9\u30c3\u30c8\u30d5\u30a9\u30fc\u30e0\u3001\u30b5\u30fc\u30d3\u30b9\u3001\u88fd\u54c1\u306f\u3001\u4ee5\u4e0b\u306e\u7c73\u56fd\u7279\u8a31\u3092\u542b\u3080\u77e5\u7684\u8ca1\u7523\u6a29\u306b\u3088\u3063\u3066\u4fdd\u8b77\u3055\u308c\u3066\u3044\u307e\u3059\u3002<\/p>\n<ul>\n<li> 7,823,207 <\/li>\n<li> 8,577,933 <\/li>\n<li> 9,055,023 <\/li>\n<li> 9,208,200 <\/li>\n<li> 9,298,796 <\/li>\n<li> 9,391,937 <\/li>\n<li> 9,549,069 <\/li>\n<li> 9,553,896 <\/li>\n<li> 9,619,533 <\/li>\n<li> 9,635,072 <\/li>\n<li> 9,641,532 <\/li>\n<li> 9,760,472 <\/li>\n<li> 9,773,037 <\/li>\n<li> 9,842,116 <\/li>\n<li> 9,860,488 <\/li>\n<li> 10,108,311 <\/li>\n<li> 10,140,382 <\/li>\n<li> 10,169,480 <\/li>\n<li> 10,180,956 <\/li>\n<li> 10,204,088 <\/li>\n<li> 10,225,360 <\/li>\n<li> 10,375,132 <\/li>\n<li> 10,419,566 <\/li>\n<li> 10,452,518 <\/li>\n<li> 10,467,629 <\/li>\n<li> 10,740,485 <\/li>\n<li> 10,757,112 <\/li>\n<li> 10,785,224 <\/li>\n<li> 10,789,324 <\/li>\n<li> 10,796,013 <\/li>\n<li> 10,831,851 <\/li>\n<li> 10,878,115 <\/li>\n<li> 10,902,081 <\/li>\n<li> 10,942,936 <\/li>\n<li> 10,970,255 <\/li>\n<li> 10,997,202 <\/li>\n<li> 11,023,667 <\/li>\n<li> 11,030,232 <\/li>\n<li> 11,036,618 <\/li>\n<li> 11,082,407 <\/li>\n<li> 11,087,082 <\/li>\n<li> 11,159,638 <\/li>\n<li> 11,169,986 <\/li>\n<li> 11,222,133 <\/li>\n<li> 11,228,642 <\/li>\n<li> 11,232,871 <\/li>\n<li> 11,256,661 <\/li>\n<li> 11,303,463 <\/li>\n<li> 11,321,342 <\/li>\n<li> 11,386,126 <\/li>\n<li> 11,416,630 <\/li>\n<li> 11,429,932 <\/li>\n<li> 11,429,943 <\/li>\n<li> 11,445,023 <\/li>\n<li> 11,489,916 <\/li>\n<li> 11,501,313 <\/li>\n<li> 11,526,573 <\/li>\n<li> 11,544,241 <\/li>\n<li> 11,551,794 <\/li>\n<li> 11,580,074 <\/li>\n<li> 11,580,095 <\/li>\n<li> 11,580,122 <\/li>\n<li> 11,593,499 <\/li>\n<li> 11,604,840 <\/li>\n<li> 11,620,290 <\/li>\n<li> 11,620,322 <\/li>\n<li> 11,720,236 <\/li>\n<li> 11,727,033 <\/li>\n<li> 11,757,993 <\/li>\n<li> 11,789,968 <\/li>\n<li> 11,811,552 <\/li>\n<li> 11,836,129 <\/li>\n<li> 11,853,359 <\/li>\n<li>11,886,452<\/li>\n<li>11,907,305<\/li>\n<li>11,928,102<\/li>\n<li>11,928,136<\/li>\n<li>12,001,394<\/li>\n<li>12,038,925<\/li>\n<li>12,106,081<\/li>\n<li>12,117,977<\/li>\n<li>12,124,443<\/li>\n<li>12,192,044<\/li>\n<li>12,200,053<\/li>\n<li>12,216,675<\/li>\n<li>12,244,597<\/li>\n<li>12,248,526<\/li>\n<li>12,254,026<\/li>\n<li>12,271,431<\/li>\n<li>12,277,094<\/li>\n<li>12,289,174<\/li>\n<li>12,306,820<\/li>\n<li>12,314,680<\/li>\n<li>12,306,806<\/li>\n<li>12,321,344<\/li>\n<li>12,347,536<\/li>\n<li>12,362,984<\/li>\n<li>12,373,400<\/li>\n<li>12,380,239<\/li>\n<li>12,400,766<\/li>\n<li>12,406,754<\/li>\n<li>12,424,304<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Veeva\u306e\u5546\u6a19 COMMON DATA ARCHITECTURE FOR LIFE SCIENCES Veeva\u767b\u9332\u306e\u5546\u6a19 CROSSIX ORGWIKI QUALITYONE SITEVAULT VAULT VEEV&hellip;<\/p>\n","protected":false},"author":80,"featured_media":0,"parent":0,"menu_order":255,"comment_status":"closed","ping_status":"closed","template":"templates\/veeva-2024.grey-bar.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-21058","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/pantheon.veeva.com\/jp\/ip\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"ja_JP\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Veeva Japan\" \/>\n\t\t<meta property=\"og:type\" content=\"website\" \/>\n\t\t<meta property=\"og:title\" content=\"\u77e5\u7684\u8ca1\u7523 | Veeva Japan\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/pantheon.veeva.com\/jp\/ip\/\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\\\/ip\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp#listItem\",\"position\":1,\"name\":\"\\u30db\\u30fc\\u30e0\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\\\/ip\\\/#listItem\",\"name\":\"\\u77e5\\u7684\\u8ca1\\u7523\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\\\/ip\\\/#listItem\",\"position\":2,\"name\":\"\\u77e5\\u7684\\u8ca1\\u7523\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp#listItem\",\"name\":\"\\u30db\\u30fc\\u30e0\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\\\/#organization\",\"name\":\"Veeva Systems Japan\",\"description\":\"The Industry Cloud for Life Sciences\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\\\/\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veeva-japan\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\\\/ip\\\/#webpage\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\\\/ip\\\/\",\"name\":\"\\u77e5\\u7684\\u8ca1\\u7523 | Veeva Japan\",\"inLanguage\":\"ja\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\\\/ip\\\/#breadcrumblist\"},\"datePublished\":\"2015-10-20T16:48:00+09:00\",\"dateModified\":\"2026-07-30T12:03:54+09:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\\\/#website\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\\\/\",\"name\":\"Veeva Japan\",\"description\":\"The Industry Cloud for Life Sciences\",\"inLanguage\":\"ja\",\"publisher\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/jp\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>\u77e5\u7684\u8ca1\u7523 | Veeva Japan<\/title>\n\n","aioseo_head_json":{"title":"\u77e5\u7684\u8ca1\u7523 | Veeva Japan","description":"","canonical_url":"https:\/\/pantheon.veeva.com\/jp\/ip\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/pantheon.veeva.com\/jp\/ip\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/jp#listItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/pantheon.veeva.com\/jp","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/jp\/ip\/#listItem","name":"\u77e5\u7684\u8ca1\u7523"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/jp\/ip\/#listItem","position":2,"name":"\u77e5\u7684\u8ca1\u7523","previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/jp#listItem","name":"\u30db\u30fc\u30e0"}}]},{"@type":"Organization","@id":"https:\/\/pantheon.veeva.com\/jp\/#organization","name":"Veeva Systems Japan","description":"The Industry Cloud for Life Sciences","url":"https:\/\/pantheon.veeva.com\/jp\/","sameAs":["https:\/\/www.linkedin.com\/company\/veeva-japan\/"]},{"@type":"WebPage","@id":"https:\/\/pantheon.veeva.com\/jp\/ip\/#webpage","url":"https:\/\/pantheon.veeva.com\/jp\/ip\/","name":"\u77e5\u7684\u8ca1\u7523 | Veeva Japan","inLanguage":"ja","isPartOf":{"@id":"https:\/\/pantheon.veeva.com\/jp\/#website"},"breadcrumb":{"@id":"https:\/\/pantheon.veeva.com\/jp\/ip\/#breadcrumblist"},"datePublished":"2015-10-20T16:48:00+09:00","dateModified":"2026-07-30T12:03:54+09:00"},{"@type":"WebSite","@id":"https:\/\/pantheon.veeva.com\/jp\/#website","url":"https:\/\/pantheon.veeva.com\/jp\/","name":"Veeva Japan","description":"The Industry Cloud for Life Sciences","inLanguage":"ja","publisher":{"@id":"https:\/\/pantheon.veeva.com\/jp\/#organization"}}]},"og:locale":"ja_JP","og:site_name":"Veeva Japan","og:type":"website","og:title":"\u77e5\u7684\u8ca1\u7523 | Veeva Japan","og:url":"https:\/\/pantheon.veeva.com\/jp\/ip\/"},"aioseo_meta_data":{"post_id":"21058","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2021-08-20 21:29:51","updated":"2026-08-23 22:26:10","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":"2026-08-21 22:21:12"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/jp\" title=\"\u30db\u30fc\u30e0\">\u30db\u30fc\u30e0<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\u77e5\u7684\u8ca1\u7523\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"\u30db\u30fc\u30e0","link":"https:\/\/pantheon.veeva.com\/jp"},{"label":"\u77e5\u7684\u8ca1\u7523","link":"https:\/\/pantheon.veeva.com\/jp\/ip\/"}],"_links":{"self":[{"href":"https:\/\/pantheon.veeva.com\/jp\/wp-json\/wp\/v2\/pages\/21058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pantheon.veeva.com\/jp\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pantheon.veeva.com\/jp\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pantheon.veeva.com\/jp\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/pantheon.veeva.com\/jp\/wp-json\/wp\/v2\/comments?post=21058"}],"version-history":[{"count":61,"href":"https:\/\/pantheon.veeva.com\/jp\/wp-json\/wp\/v2\/pages\/21058\/revisions"}],"predecessor-version":[{"id":52627,"href":"https:\/\/pantheon.veeva.com\/jp\/wp-json\/wp\/v2\/pages\/21058\/revisions\/52627"}],"wp:attachment":[{"href":"https:\/\/pantheon.veeva.com\/jp\/wp-json\/wp\/v2\/media?parent=21058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}