{"id":59162,"date":"2025-04-29T07:10:25","date_gmt":"2025-04-29T12:10:25","guid":{"rendered":"https:\/\/www.veeva.com\/la\/?page_id=59162"},"modified":"2026-08-31T13:29:19","modified_gmt":"2026-08-31T19:29:19","slug":"vault-ai","status":"publish","type":"page","link":"https:\/\/pantheon.veeva.com\/la\/products\/vault-ai\/","title":{"rendered":"Vault AI"},"content":{"rendered":"<style>\n@media (max-width:1199.98px) {\n.veeva-2024 .video-player-module--multiple .sub-video-nav-wrapper__content .sub-video-nav:nth-of-type(n+4) {\ndisplay: grid;\n}\n}\n.veeva-2024 .sub-video-nav__content {\ngap: 6px;\n}\n.veeva-2024 .sub-video-nav--stacked {\npadding: 12px 15px;\ngap: 14px;\n}\n.veeva-2024 .video-player-module__video-info h5 {\nfont-size: 16px;\nfont-weight: 400;\n}<\/p>\n<p>.veeva-2024 .video-player-module__video-info p {\nfont-size: 24px;\nfont-weight: 600;\n}<\/p>\n<p>.veeva-2024 .video-player-module__video-info {\ndisplay: flex;\nflex-direction: column;\ngap: 3px;\n}\n@media (min-width:1200px) {\n.veeva-2024 .video-player-module--multiple .sub-video-nav-wrapper {\nflex-grow: 1;\nmax-width: 440px;\n}\n}\n.veeva-2024 .tab-block .tablist {\nmargin-bottom: 5px;\n}<\/p>\n<p>.veeva-2024 .alert-news__copy {\nmargin-right: -15px!important;\n}\n.veeva-2024 strong {\nfont-weight: 600;\n}\n@media (min-width:768px) {\n.veeva-2024 .veeva-footer-2024 {\npadding: 146px 0 64px;\n}\n}\n@media (min-width:768px) {\n.veeva-2024 .hero-centered {\npadding: 80px 0;\n}\n}\n.veeva-2024 .copy-container>img {\nmax-height: 45px;\nmax-width: unset;\nwidth: unset;\nheight: 60px;\nmargin-bottom: 2rem;\n}\n.veeva-2024 .quote-card {\n\tbackground: #FD6F08;color:white;\n}<\/p>\n<p>.veeva-2024 #hero.hero-centered--image {\n--mobile-image: url(https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/04\/AI-page-hero-1920x560@2x.png);\n--desktop-image: url(https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/04\/AI-page-hero-1920x560@2x.png);\n}\n@media (min-width:768px) {\n.veeva-2024 .h1, .veeva-2024 h1 {\nfont-size: 48px;\n}\n}\n.veeva-2024 h2 {\nfont-size: 32px;\n}\n@media (min-width:768px) {\n.veeva-2024 .h2, .veeva-2024 h2 {\nfont-size: 38px;\n}\n}\n.veeva-2024 .ai-top-content {\nmax-width:1140px;margin-left:auto;margin-right:auto;margin-top:80px;margin-bottom:60px;\n}<\/p>\n<p>.veeva-2024 .ai-top-content .agents h3 {\ncolor:#F5670E;margin-bottom:12px;margin-top:35px;\nfont-weight:500;font-size:26px\n}\n@media (min-width:768px) {\n.veeva-2024 .ai-top-content .agents h3 {\ncolor:#F5670E;margin-bottom:12px;margin-top:35px;\nfont-weight:500;font-size:30px\n}\n}\n.veeva-2024 .ai-top-content .agents p {\nfont-size: 16px;\n\/* max-width: 450px; *\/\nline-height: 140%;\n}\n.veeva-2024 .ai-top-content .bottom-copy h4 {\nmargin-top:20px;margin-bottom:6px;\nfont-weight:500;font-size:24px\n}<\/p>\n<p>@media (min-width:768px) {\n.veeva-2024 .ai-top-content .bottom-copy h4 {\nmargin-top:20px;margin-bottom:6px;\nfont-weight:500;font-size:28px\n}\n}<\/p>\n<p>.veeva-2024 .ai-top-content .bottom-copy p {\nfont-size:16px;max-width:800px;line-height: 140%;\nmargin-left:auto; margin-right:auto;\n}\n.veeva-2024 .z-pattern__image-wrapper {\nmargin-bottom:20px;\n}\n@media (min-width:768px) {\n.veeva-2024 .z-pattern__image-wrapper {\nborder-radius: 20px;\nmax-width: 80vh;\n}\n}\n.veeva-2024 .ai-quote p span {\ndisplay:inline-block;width:60px;border-top:1px solid;margin-bottom:22px\n}\n.veeva-2024 .vid-sub-text {\nfont-size:16px;\ntext-align:center;\n}\n@media (min-width:991px) {\n.veeva-2024 .vid-sub-text {\nfont-size:16px;\ntext-align:left;\n}\n}\n.veeva-2024 .ai-quote p {\ntext-align:center;\nfont-size:20px;\nmargin-bottom:15px;\n}<\/p>\n<p>@media (min-width:991px) {\n.veeva-2024 .ai-quote p {\ntext-align:left;\nfont-size:26px;\nmargin-bottom:20px;\n}\n}\n.veeva-2024 .ai-quote p.peter {\nfont-size:16px;\n}<\/p>\n<p>@media (min-width:991px) {\n.veeva-2024 .ai-quote p.peter {\nfont-size:18px;\n}\n}<\/p>\n<p>.veeva-2024 .summit-footer {\nborder-radius: 50px;\nbackground: linear-gradient(319deg, #449FD7 19.73%, #1A76A3 89.17%);\nbox-shadow: 0px 4px 24px 0px rgba(0, 0, 0, 0.15);padding:70px 5% 40px 10%;color:white;\nmargin-bottom:-50px;\n}\n.veeva-2024 .summit-footer .summit-title, .veeva-2024 .summit-footer .summit  {\npadding-bottom:15px;\n}\n.veeva-2024 .summit-title div {\nfont-size:24px;\n}\n.veeva-2024 .summit-title h3 {\nfont-size:40px;margin-top:7px;margin-bottom:15px;\n}\n.veeva-2024 .summit div {\nfont-size:18px;margin-bottom:15px;\n}\n.veeva-2024 .summit h4 {\nfont-size:25px\n}\n.veeva-2024 .carousel {<\/p>\n<p>box-shadow: 0 .99px 11.8px 0 rgba(0,0,0,.05),0 2.75px 32.7px 0 rgba(0,0,0,.07),0 6.6px 78.7px 0 rgba(0,0,0,.09),0 22px 30px 0 rgba(0,0,0,.14);\n}<\/p>\n<p>.veeva-2024 .vp-image-text p strong {\nfont-weight: 600;\ncolor: #F5670E;\n}\n.veeva-2024 .vp-image-text {\ndisplay: inline-grid;\nmargin: auto;\ntext-align: center;\nmargin-top: 30px;\n}\n@media (min-width:768px) {\n.veeva-2024 .vp-image-text {\ntext-align: left;\nmargin-top: 0px;\npadding-left: 30px;\n}\n}\n@media (min-width:768px) {\n.veeva-2024 .marquee-subpoints__list h6, .veeva-2024 .vp-image-text h6 {\nfont-size: 24px;\n}\n}\n.veeva-2024 .vp-image-text p.hr {\n\/* border-bottom: 1px solid #D6D6D6; *\/\nborder-bottom: 1px solid #999;\npadding-bottom: 20px;\nmargin-bottom: 20px;\n}<\/p>\n<p>@media (min-width:768px) {\n.veeva-2024 .vp-image-text p.last{\nmargin-bottom: 40px;\n}\n}<\/p>\n<p>@media (min-width:768px) {\n.veeva-2024 .sub-video-nav--stacked--light .sub-video-nav__content p {\nfont-size: 16px;\ncolor:black;\n}\n.veeva-2024 .sub-video-nav--stacked--light .sub-video-nav__content h6 {\ncolor: #636669;\nfont-size: 14px;\n}\n}\n@media (min-width:768px) {\n.veeva-2024 .z-pattern__image-wrapper {\nborder-radius: 20px;\nmax-width: 100vh;\n}\n}<\/p>\n<p>\/* tabs *\/<\/p>\n<p>.veeva-2024 .tab-block--light .tablist .tablist-link {\nbackground: #eef1f5;\ncolor: #01040b;\nborder-radius: 10px 10px 0px 0px;\nbox-shadow: none;\n}<\/p>\n<p>.veeva-2024 .tab-block--light .tablist .tablist-link.active, .veeva-2024 .tab-block--light .tablist .tablist-link:hover {\nbackground: linear-gradient(132deg,#1b2f54 -3.62%,#1b3055 9.38%,#1b3157 19.95%,#1b345a 28.48%,#1b385e 35.33%,#1b3c62 40.88%,#1b4168 45.49%,#1b466e 49.55%,#1b4c74 53.43%,#1b527b 57.49%,#1a5982 62.1%,#1a5f89 67.65%,#1a6590 74.5%,#1a6b97 83.03%,#1a719d 93.6%,#1a76a3 106.6%);\ncolor:white;\nfont-weight:600;\n}<\/p>\n<p>.veeva-2024 .tablist .tablist-link {\nfont-weight:400;\nopacity: 1;\n}<\/p>\n<p>.veeva-2024 .tablist.tablist-text .nav-pills {\ngap: 24px;\nborder-bottom: 1px solid #eee;\n}<\/p>\n<p>@media (min-width:767px) {\n.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:nth-child(2), \n.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:nth-child(3),\n.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:nth-child(4),\n.veeva-2024 .resource-block__cards.resource-block__cards--featured .resource-card:nth-child(5) {\ngrid-column: span 3;\nmin-height: 160px;\n}\n}<\/p>\n<p>@media (min-width:768px) {\n.veeva-2024 .resource-block-featured .resource-card .resource-card__text .h5, .veeva-2024 .resource-block-featured .resource-card .resource-card__text h5 {\nfont-size: 20px;\n}\n}<\/p>\n<p>@media (min-width:767px) {\n.veeva-2024 .resource-block-featured .resource-card .resource-card__cta {\ndisplay: flex;\n}\n}\n<\/style>\n<p><main class=\"veeva-2024\"><\/p>\n<p><!-- Hero --><\/p>\n<section id=\"hero\" class=\"hero-centered hero-centered--image\">\n<div class=\"container copy-container copy-container--center\">\n\t\t<img decoding=\"async\" alt=\"Veeva AI\" class=\"img-responsive\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2026\/06\/Vault-AI_wht_300x60.png\"><\/p>\n<h1>Vault AI: IA Ag\u00e9ntica en Vault Platform<br class=\"d-none d-lg-block\"> y Agentes de IA en Aplicaciones Veeva<\/h1>\n<p><strong>IA profunda que es simple, segura y compliant para empresas de ciencias de la salud de todos los tama\u00f1os.<\/strong><\/p>\n<p><a style=\"margin-top:18px\" class=\"button-primary button-primary--gradient button-primary--arrow-downward\" href=\"#AI-in-action\" target=\"_self\" rel=\"noopener\"> Ver Vault AI en Acci\u00f3n <\/a><\/p>\n<p class=\"d-none\"><em>First release planned for December 2025<\/em><\/p>\n<\/p><\/div>\n<\/section>\n<p><!-- Quote - Tabs, Light, Single Quote Card --><\/p>\n<section class=\"ai-top-content\" style=\"margin-top:60px\">\n<div class=\"container\">\n<div class=\"copy-container copy-container--center copy-container--eyebrow-gradient\" style=\"margin-bottom:10px;\">\n<h2>IA Profunda para Ciencias de la Salud<\/h2>\n<p style=\"max-width:1200px;font-size:20px\"> Vault AI is IA ag\u00e9ntica integrada directamente en Vault Platform, adem\u00e1s de agentes de aplicaciones espec\u00edficos de la industria presentes en todas las soluciones de Veeva.<\/p>\n<\/p><\/div>\n<div class=\"row agents text-center\">\n<div class=\"col-md-6\" style=\"padding:0px 30px;\">\n<h3 style=\"text-align:center\">IA en Vault Platform<\/h3>\n<p>\n\t\t\t\tVeeva Vault Platform es una plataforma \u00fanica que integra <strong>datos, contenido y agentes.<\/strong> De esta manera, tus Vault AI Agents tienen un acceso directo y seguro a la informaci\u00f3n y al contenido, trabajando sin fricciones dentro de todas tus aplicaciones Veeva.\n\t\t\t\t<\/p>\n<\/p><\/div>\n<div class=\"col-md-6\" style=\"padding:0px 30px;\">\n<h3 style=\"text-align:center\">Vault AI Agents<\/h3>\n<p>\n\t\t\t\t<strong>Aplicaciones de IA profunda, no simples kits de herramientas.<\/strong> Los Vault AI Agents operan dentro de las aplicaciones de Veeva, cuentan con indicaciones (prompts) y salvaguardas profundos y espec\u00edficos para cada soluci\u00f3n, y se ejecutan en contexto gracias a su acceso total a datos, documentos y flujos de trabajo.\n\t\t\t\t<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"bottom-copy text-center\" style=\"max-width:1000px;margin:auto;margin-top:35px;\">\n<h4>Aplicaciones de IA Flexibles y Seguras \u2013 Siempre en Evoluci\u00f3n<\/h4>\n<p>\nMejoramos y actualizamos de forma continua los <strong>Vault AI Agents<\/strong> est\u00e1ndar e introducimos nuevos agentes a lo largo del a\u00f1o a trav\u00e9s de nuestros lanzamientos de producto tres veces por a\u00f1o. Adem\u00e1s, puedes configurar y expandir tus Vault AI Agents o crear tus propios <strong>agentes personalizados Custom Agents<\/strong>.\n\t\t\t<\/p>\n<p>\nLos Vault AI Agents utilizan modelos de lenguaje extenso (LLMs) de Anthropic y Amazon, alojados en Amazon Bedrock. Los agentes personalizados creados con Vault AI emplean modelos alojados por Veeva o modelos proporcionados por el cliente y alojados en Amazon Bedrock o Microsoft Azure AI Foundry. Independientemente del modelo de implementaci\u00f3n o del LLM utilizado, Vault AI mantiene tus datos completamente seguros.\n\t\t\t<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"section-rounded\" style=\"max-width:990px;padding:50px 0 50px 0;background:#eef1f5;margin:auto;margin-bottom:80px;\">\n<div class=\"container\">\n<div class=\"row\" style=\"max-width:900px;margin:auto;display:flex;align-items:center;\">\n<div class=\"col-md-6 text-center\">\n\t\t\t\t<img decoding=\"async\" style=\"width:100%;max-width:350px;margin:auto\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/08\/vault-platform-graphic-400x402@2x.png\" alt=\"\">\n\t\t\t<\/div>\n<div class=\"col-md-6 text-center\">\n<div class=\"vp-image-text\">\n<p style=\"font-size:14px;margin-bottom:5px;\"><strong>VEEVA VAULT PLATFORM<\/strong>\n<\/p>\n<h6 style=\"color:#111;margin-bottom:25px\">Datos, Contenido, Agentes<\/h6>\n<p class=\"hr\">\n\t\t\t\t\t\t<strong>IA ag\u00e9ntica<\/strong> integrada en Vault.\n\t\t\t\t\t<\/p>\n<p class=\"hr\">\n\t\t\t\t\t\tAcceso directo y seguro a <strong>datos y contenido.<\/strong>\n\t\t\t\t\t<\/p>\n<p class=\"last\">\n\t\t\t\t\t\t<strong>Configura<\/strong> tus Vault AI Agents <strong>o crea<\/strong> agentes personalizados.\n\t\t\t\t\t<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"section-rounded\" style=\"z-index:2;padding-top:80px;background: radial-gradient(155.15% 99.46% at 56.51% 50.08%,#030d1f 0,#1a719d 100%);color:white\">\n<div class=\"container\">\n<div class=\"copy-container copy-container--center copy-container--eyebrow-gradient\">\n<h3 style=\"font-size:34px;line-height: 1.3;\">Mayor Productividad desde el \u00c1rea Cl\u00ednica hasta la Comercial<\/h3>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"quote-tabs quote-tabs--light\" style=\"color:white;margin-top:50px;background:none;margin-bottom:80px;\">\n<div class=\"quote-tabs__content\">\n<div class=\"container\">\n<div class=\"row\" style=\"align-items: center;\">\n<div class=\"col-lg-6\" style=\"padding:10px 20px;\">\n<div class=\"wistia_embed wistia_async_ciaijvl109 popover=true popoverContent=link\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/10\/ai-summit-peter-thumbnail.png\" alt=\"\" \/>\n\t\t\t\t\t<\/div>\n<p>\t\t\t\t\t\t\t\t<!-- \n\t\t\t\t\t\t\t\t\n\n<div class=\"wistia_responsive_padding\" style=\"padding: 56.25% 0 0 0; position: relative\">\n\t\t\t\t\t\t\t\t\t\n\n<div class=\"wistia_responsive_wrapper\" style=\"height: 100%; left: 0; position: absolute; top: 0; width: 100%\">\n\t\t\t\t\t\t\t\t\t\t\n\n<div class=\"wistia_embed wistia_async_ciaijvl109 autoplay=false endVideoBehavior=loop popover=true\" style=\"height: 100%; width: 100%\"><\/div>\n\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\n\n \t\t\t\t\t\t\t\t--><\/p>\n<div class=\"vid-sub-text d-none\">\n\t\t\t\t\t\t\t<strong>Veeva AI Overview<\/strong>, 2025 R&#038;D and Quality Summit Keynote\n\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<div class=\"col-lg-6 ai-quote\" style=\"padding:8px 20px;\">\n<p style=\"font-weight:300\">\n&#8220;Vault AI consiste en agentes est\u00e1ndar integrados directamente en Vault en todas las aplicaciones para ayudarte a hacer tu trabajo y ser m\u00e1s productivo. Vault AI utiliza los datos y documentos de tu propio Vault, por lo que ser\u00e1 mucho m\u00e1s preciso al responder a tus preguntas y asistirte. Falcon entregar\u00e1 agentes est\u00e1ndar que realizar\u00e1n la mayor parte del trabalho: es trabajo ag\u00e9ntico&#8221;.\n\t\t\t\t\t\t\t\t\t<\/p>\n<p style=\"margin:0\">\n\t\t\t\t\t\t<span><\/span>\n\t\t\t\t\t\t<\/p>\n<p class=\"peter\">\n\t\t\t\t\t\t\t<strong>Jim Reilly<\/strong>, Presidente de Development Cloud y EVP de Estrategia Global\n\t\t\t\t\t\t<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n<p><!-- Video Player Multiple With Tabs  --><\/p>\n<section id=\"AI-in-action\" class=\"tab-block tab-block-customer video-player-tabs tab-block--light\" style=\"margin-bottom:60px\">\n<div class=\"container\">\n        <!-- copy container --><\/p>\n<div class=\"copy-container copy-container--center copy-container--eyebrow-gradient\">\n<h3>\n                Descubre C\u00f3mo los Agentes de Aplicaciones Profundas Incrementan tu Productividad<br \/>\n            <\/h3>\n<div class=\"copy-container copy-container--center copy-container--eyebrow-gradient\">\n<p>\n                Para activar los subt\u00edtulos, haga clic en el bot\u00f3n &#8220;CC&#8221; en la barra inferior del video y seleccione el idioma deseado.\n            <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>    <!-- content --><\/p>\n<div class=\"tab-block__content\">\n        <!-- tablist: text --><\/p>\n<div class=\"tablist tablist-text tablist--light\">\n<ul class=\"nav nav-pills\" role=\"tablist\">\n<li class=\"nav-item\" role=\"presentation\">\n                    <button id=\"Comercial-tab\" class=\"nav-link tablist-link\">Comercial<\/button>\n                <\/li>\n<li class=\"nav-item\" role=\"presentation\">\n                    <button id=\"Cl\u00ednico-tab\" class=\"nav-link tablist-link\">Cl\u00ednico<\/button>\n                <\/li>\n<li class=\"nav-item\" role=\"presentation\">\n                    <button id=\"Regulatorio-tab\" class=\"nav-link tablist-link\">Regulatorio<\/button>\n                <\/li>\n<li class=\"nav-item\" role=\"presentation\">\n                    <button id=\"safety-tab\" class=\"nav-link tablist-link\">Safety<\/button>\n                <\/li>\n<li class=\"nav-item\" role=\"presentation\">\n                    <button id=\"Calidad-tab\" class=\"nav-link tablist-link\">Calidad<\/button>\n                <\/li>\n<\/ul><\/div>\n<p>        <!-- tablist content --><\/p>\n<div class=\"container tab-content\">\n<p>         <!-- tablist content item 1 --><\/p>\n<div class=\"tab-pane\">\n                <!-- video player block --><br \/>\n                <!-- ** unique id on block ** --><\/p>\n<section id=\"AI-in-action-commercial\" class=\"video-player-demos video-player-demos--light my-0\">\n<div class=\"video-player-module video-player-module--multiple\">\n<div class=\"video-player-module__video\">\n<div class=\"video-player-module__wistia-wrapper\">\n                                <!-- NOTE: need to add wistia code + aspect ratio --><br \/>\n                                <!-- adjust video aspect ratio here --><\/p>\n<div class=\"wistia_responsive_padding\" style=\"padding: 56.25% 0 0 0; position: relative\">\n<div class=\"wistia_responsive_wrapper\" style=\"height: 100%; left: 0; position: absolute; top: 0; width: 100%\">\n                                        <!-- add class here : wistia_async_{wistia-id} --><\/p>\n<div class=\"wistia_embed wistia_async_zezlim9sh2\" style=\"height: 100%; width: 100%\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>                            <!-- NOTE: Video Info added automatically -->\n                        <\/div>\n<p>                        <!-- sub video nav wrapper, light --><\/p>\n<div class=\"video-player-module__video-nav sub-video-nav-wrapper sub-video-nav-wrapper--light\">\n<div class=\"sub-video-nav-wrapper__content\">\n                                <!-- NOTE: Sub Video Nav added automatically -->\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section><\/div>\n<p>            <!-- tablist content item 2 --><\/p>\n<div class=\"tab-pane\">\n                <!-- video player block --><\/p>\n<section id=\"AI-in-action-clinical\" class=\"video-player-demos video-player-demos--light my-0\">\n<div class=\"video-player-module video-player-module--multiple\">\n<div class=\"video-player-module__video\">\n<div class=\"video-player-module__wistia-wrapper\">\n                                <!-- NOTE: need to add wistia code + aspect ratio --><br \/>\n                                <!-- adjust video aspect ratio here --><\/p>\n<div class=\"wistia_responsive_padding\" style=\"padding: 56.25% 0 0 0; position: relative\">\n<div class=\"wistia_responsive_wrapper\" style=\"height: 100%; left: 0; position: absolute; top: 0; width: 100%\">\n                                        <!-- add class here : wistia_async_{wistia-id} --><\/p>\n<div class=\"wistia_embed wistia_async_28ucth5dgx\" style=\"height: 100%; width: 100%\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>                            <!-- NOTE: Video Info added automatically -->\n                        <\/div>\n<p>                        <!-- sub video nav wrapper, light --><\/p>\n<div class=\"video-player-module__video-nav sub-video-nav-wrapper sub-video-nav-wrapper--light\">\n<div class=\"sub-video-nav-wrapper__title\"><\/div>\n<div class=\"sub-video-nav-wrapper__content\">\n                                <!-- NOTE: Sub Video Nav added automatically -->\n                            <\/div>\n<div class=\"sub-video-nav-wrapper__bottom\">\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section><\/div>\n<p>            <!-- tablist content item 3 --><\/p>\n<div class=\"tab-pane\">\n                <!-- video player block --><\/p>\n<section id=\"AI-in-action-regulatory\" class=\"video-player-demos video-player-demos--light my-0\">\n<div class=\"video-player-module video-player-module--multiple\">\n<div class=\"video-player-module__video\">\n<div class=\"video-player-module__wistia-wrapper\">\n                                <!-- NOTE: need to add wistia code + aspect ratio --><br \/>\n                                <!-- adjust video aspect ratio here --><\/p>\n<div class=\"wistia_responsive_padding\" style=\"padding: 56.25% 0 0 0; position: relative\">\n<div class=\"wistia_responsive_wrapper\" style=\"height: 100%; left: 0; position: absolute; top: 0; width: 100%\">\n                                        <!-- add class here : wistia_async_{wistia-id} --><\/p>\n<div class=\"wistia_embed wistia_async_g7pihis37d\" style=\"height: 100%; width: 100%\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>                            <!-- NOTE: Video Info added automatically -->\n                        <\/div>\n<p>                        <!-- sub video nav wrapper, light --><\/p>\n<div class=\"video-player-module__video-nav sub-video-nav-wrapper sub-video-nav-wrapper--light\">\n<div class=\"sub-video-nav-wrapper__title\">\n<h5>Recommended Videos<\/h5>\n<\/p><\/div>\n<div class=\"sub-video-nav-wrapper__content\">\n                                <!-- NOTE: Sub Video Nav added automatically -->\n                            <\/div>\n<div class=\"sub-video-nav-wrapper__bottom\">\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section><\/div>\n<p>            <!-- tablist content item 4 --><\/p>\n<div class=\"tab-pane\">\n                <!-- video player block --><\/p>\n<section id=\"AI-in-action-safety\" class=\"video-player-demos video-player-demos--light my-0\">\n<div class=\"video-player-module video-player-module--multiple\">\n<div class=\"video-player-module__video\">\n<div class=\"video-player-module__wistia-wrapper\">\n                                <!-- NOTE: need to add wistia code + aspect ratio --><br \/>\n                                <!-- adjust video aspect ratio here --><\/p>\n<div class=\"wistia_responsive_padding\" style=\"padding: 56.25% 0 0 0; position: relative\">\n<div class=\"wistia_responsive_wrapper\" style=\"height: 100%; left: 0; position: absolute; top: 0; width: 100%\">\n                                        <!-- add class here : wistia_async_{wistia-id} --><\/p>\n<div class=\"wistia_embed wistia_async_5km2gk3k6s\" style=\"height: 100%; width: 100%\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>                            <!-- NOTE: Video Info added automatically -->\n                        <\/div>\n<p>                        <!-- sub video nav wrapper, light --><\/p>\n<div class=\"video-player-module__video-nav sub-video-nav-wrapper sub-video-nav-wrapper--light\">\n<div class=\"sub-video-nav-wrapper__title\">\n                            <\/div>\n<div class=\"sub-video-nav-wrapper__content\">\n                                <!-- NOTE: Sub Video Nav added automatically -->\n                            <\/div>\n<div class=\"sub-video-nav-wrapper__bottom\">\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section><\/div>\n<p>            <!-- tablist content item 5 --><\/p>\n<div class=\"tab-pane\">\n                <!-- video player block --><\/p>\n<section id=\"AI-in-action-quality\" class=\"video-player-demos video-player-demos--light my-0\">\n<div class=\"video-player-module video-player-module--multiple\">\n<div class=\"video-player-module__video\">\n<div class=\"video-player-module__wistia-wrapper\">\n                                <!-- NOTE: need to add wistia code + aspect ratio --><br \/>\n                                <!-- adjust video aspect ratio here --><\/p>\n<div class=\"wistia_responsive_padding\" style=\"padding: 56.25% 0 0 0; position: relative\">\n<div class=\"wistia_responsive_wrapper\" style=\"height: 100%; left: 0; position: absolute; top: 0; width: 100%\">\n                                        <!-- add class here : wistia_async_{wistia-id} --><\/p>\n<div class=\"wistia_embed wistia_async_oywvdvsy3b\" style=\"height: 100%; width: 100%\"><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>                            <!-- NOTE: Video Info added automatically -->\n                        <\/div>\n<p>                        <!-- sub video nav wrapper, light --><\/p>\n<div class=\"video-player-module__video-nav sub-video-nav-wrapper sub-video-nav-wrapper--light\">\n<div class=\"sub-video-nav-wrapper__title\"><\/div>\n<div class=\"sub-video-nav-wrapper__content\">\n                                <!-- NOTE: Sub Video Nav added automatically -->\n                            <\/div>\n<div class=\"sub-video-nav-wrapper__bottom\">\n                            <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n<section>\n<div class=\"quote-tabs quote-tabs--light section-rounded\" style=\"padding:80px 0 30px 0;margin-top:80px;background: #eef1f5;;margin-bottom:80px;\">\n<div class=\"container copy-container copy-container--center\">\n<h6 style=\"font-size: 26px;color:#F5670E;\">\n          Veeva AI<br \/>\n        <\/h6>\n<h3 style=\"margin-bottom:25px;font-size:38px\"> Habilitando A\u00fan M\u00e1s a la Industria<\/h3>\n<p style=\"max-width:1150px;font-size:19px\">Vault AI forma parte de Veeva AI, una estrategia enfocada en garantizar una IA de alto valor que impulse una mayor eficiencia y efectividad en tu negocio.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"resource-block-featured resource-block-featured--light section-contained-width--xl\" style=\"padding-top:10px;padding-bottom:160px;\">\n<div class=\"container\" style=\"max-width:1200px\">\n<div class=\"container copy-container copy-container--center\" style=\"margin-bottom:50px;\">\n<h3>Recursos<\/h3>\n<\/p><\/div>\n<div class=\"resource-block__cards resource-block__cards--featured resource-block__cards--featured--6\">\n\t\t\t<a id=\"resource-card--summit\" class=\"d-none\"><br \/>\n\t\t\t<\/a><\/p>\n<p>\t \t  <a class=\"resource-card\" href=\"\/resources\/veeva-ai-agents-to-be-released-across-all-veeva-applications\/\"><\/p>\n<div class=\"resource-card__text\">\n<h5 style=\"height: auto;\">Veeva adquiere Copli y lanza Veeva Falcon MLR para acelerar la revisi\u00f3n de contenido<\/h5>\n<div class=\"resource-card__cta button-text-link button-text-link--black\">\n\t\t\t<span class=\"label\">Leer Comunicado de Prensa<\/span><br \/>\n\t\t\t<span class=\"underline\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<p>\t\t\t\t\t<\/a><\/p>\n<p>                   <a class=\"resource-card\" href=\"https:\/\/www.veeva.com\/la\/resources\/openevidence-y-veeva-anuncian-la-alianza-open-vista\/\"><\/p>\n<div class=\"resource-card__text\">\n<h5 style=\"height: auto;\">Puntos Clave del Keynote: Habilitando Agentic Biopharma&#x2122;: Agentes de IA trabajando para ti y a tu lado<\/h5>\n<div class=\"resource-card__cta button-text-link button-text-link--black\">\n\t\t\t<span class=\"label\">Ver Video<\/span><br \/>\n\t\t\t<span class=\"underline\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<p>\t\t\t\t\t<\/a><\/p>\n<p>\t\t  <a class=\"resource-card\" href=\"\/meet-veeva\/partners\/ai\/\"><\/p>\n<div class=\"resource-card__text\">\n<h5>Programa de Partners de Veeva AI: Acceso tecnol\u00f3gico para desarrollar soluciones de IA<\/h5>\n<div class=\"resource-card__cta button-text-link button-text-link--black\">\n\t\t\t\t<span class=\"label\">M\u00e1s Informaci\u00f3n<\/span><br \/>\n\t\t\t\t<span class=\"underline\"><\/span>\n\t\t\t  <\/div>\n<\/p><\/div>\n<p>\t\t  <\/a><\/p>\n<p>\t\t  <a class=\"resource-card\" href=\"https:\/\/www.veeva.com\/la\/products\/vault-platform\/\"><\/p>\n<div class=\"resource-card__text\">\n<h5 style=\"height: auto;\">Veeva anuncia Falcon, una plataforma ag\u00e9ntica y agentes est\u00e1ndar para ofrecer trabajo ag\u00e9ntico en el desarrollo de f\u00e1rmacos<\/h5>\n<div class=\"resource-card__cta button-text-link button-text-link--black\">\n\t\t\t<span class=\"label\">Leer Comunicado de Prensa<\/span><br \/>\n\t\t\t<span class=\"underline\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<p>\t\t\t\t\t<\/a><\/p><\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"d-none resource-block-cards resource-block-cards--light\" id=\"resource-block-0\"  style=\"padding:0px 0 160px 0;margin-bottom:0;margin-top:0;background: white\">\n<div class=\"container\">\n<div class=\"container copy-container copy-container--center\" style=\"margin-bottom:50px;\">\n<h6 style=\"font-size: 26px;color:#F5670E;\">\n          Veeva Connect<br \/>\n        <\/h6>\n<h3 style=\"margin-bottom:25px;font-size:38px\"> S\u00famate a la Conversaci\u00f3n en Veeva Connect<\/h3>\n<p style=\"font-size:18px;\">El espacio donde los clientes y los l\u00edderes de producto de Veeva comparten informaci\u00f3n e ideas.<\/p>\n<\/p><\/div>\n<div class=\"resource-block__cards resource-block__cards--gridded\">\n<p><a id=\"\" class=\"resource-card resource-card--light\" href=\"\/resources\/veeva-ai-agents-to-be-released-across-all-veeva-applications\/\" target=\"_self\" rel=\"noopener\"><\/p>\n<div class=\"resource-card__text\">\n<h6>Leer Comunicado de Prensa<\/h6>\n<h5>Veeva adquiere Copli y lanza Veeva Falcon MLR para acelerar la revisi\u00f3n de contenido<\/h5>\n<\/div>\n<div class=\"resource-card__media\"><img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/04\/Veeva-AI_340x240.png\" alt=\"\"><\/div>\n<p><\/a><\/p>\n<p><a id=\"\" class=\"resource-card resource-card--light\" href=\"https:\/\/veevaconnect.com\/communities\/BkCLwI28IAA\/content\" target=\"_blank\" rel=\"noopener\"><\/p>\n<div class=\"resource-card__text\">\n<h6>Unirse a la Conversaci\u00f3n<\/h6>\n<h5>S\u00famate a la Conversaci\u00f3n en Veeva Connect<\/h5>\n<\/div>\n<div class=\"resource-card__media\"><img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/10\/resource-tile-veeva-connect-340x240@2x.png\" alt=\"\"><\/div>\n<p><\/a><\/p>\n<p><a id=\"\" class=\"resource-card resource-card--light\" href=\"\/meet-veeva\/partners\/ai\/\" target=\"_self\" rel=\"noopener\"><\/p>\n<div class=\"resource-card__text\">\n<h6>M\u00e1s Informaci\u00f3n<\/h6>\n<h5>Programa de Partners de Veeva AI: Acceso tecnol\u00f3gico para desarrollar soluciones de IA<\/h5>\n<\/div>\n<div class=\"resource-card__media\"><img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/10\/resource-tile-veeva-ai-340x240@2x.png\" alt=\"\"><\/div>\n<p><\/a><\/p>\n<p><a id=\"\" class=\"resource-card resource-card--light\" href=\"\/products\/vault-platform\/\" target=\"_self\" rel=\"noopener\"><\/p>\n<div class=\"resource-card__text\">\n<h6>Leer Comunicado de Prensa<\/h6>\n<h5>Veeva anuncia Falcon, una plataforma ag\u00e9ntica y agentes est\u00e1ndar para ofrecer trabajo ag\u00e9ntico en el desarrollo de f\u00e1rmacos<\/h5>\n<\/div>\n<div class=\"resource-card__media\"><img decoding=\"async\" src=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2024\/11\/resource-logo-tile-vault-platform-340x240@2x.png\" alt=\"\"><\/div>\n<p><\/a>                <\/div>\n<\/p><\/div>\n<\/section>\n<section class=\"hero-contained hero-contained--gradient hero-contained--footer-fix\">\n<div class=\"container copy-container copy-container--center\">\n<h3>Impulsa Interacciones de Clientes M\u00e1s Impactantes<\/h3>\n<div class=\"copy-container__buttons\">\n\t\t\t\t\t<a class=\"button-primary button-primary--gradient\" href=\"\/la\/contact-us\/\" target=\"_self\" rel=\"noopener\">Cont\u00e1ctanos<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n<\/p><\/div>\n<\/section>\n<p><\/main><\/p>\n<p><script src=\"https:\/\/cdn.jsdelivr.net\/npm\/bootstrap@5.0.2\/dist\/js\/bootstrap.bundle.min.js\" integrity=\"sha384-MrcW6ZMFYlzcLA8Nl+NtUVF0sA7MsXsP1UyJoMp4YLEuNSfAP+JcXn\/tWtIaxVXM\" crossorigin=\"anonymous\"><\/script><br \/>\n<script src=\"https:\/\/www.veeva.com\/wp-content\/themes\/veeva2015\/assets\/js\/bundle.min.js?ver=1.3\" id=\"component-library-js\" data-cookieconsent=\"ignore\"><\/script><\/p>\n<p><script>\n            const videoBlockIdList = [\n            \t\"AI-in-action-commercial\",\n            \t\"AI-in-action-clinical\",                \n                \"AI-in-action-regulatory\",     \n                \"AI-in-action-safety\",                \n                \"AI-in-action-quality\"<\/p>\n<p>            ]; <!-- unique block ids -->\n            const showVideoInfo = true;<\/p>\n<p>            <!-- example data list -->\n            const videoData1 = [\n                {\n\t\t\t\t\twistiaID: \"zezlim9sh2\", <!-- Required. -->\n\t\t\t\t\ttitle: \"Veeva AI para CRM - Spotlight\", <!-- Optional -->\n\t\t\t\t\tdescription: \"Agente de voz y agente de texto libre\", <!-- Optional -->\n\t\t\t\t\t<!-- image: \"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/10\/ai-crm-intro-slide_voice-free-text-agents_small-thumb.png\", --><\/p>\n<p>\t\t\t\t},\n\t\t\t\t{\n\t\t\t\t\twistiaID: \"uovctag09r\", <!-- Required. -->\n\t\t\t\t\ttitle: \"Veeva AI para CRM - Spotlight \", <!-- Optional -->\n\t\t\t\t\tdescription: \"Agente de prellamada y agente de medios\", <!-- Optional -->\n                                       <!-- image: \"https:\/\/www.veeva.com\/wp-content\/uploads\/2025\/10\/ai-crm-intro-slide_pre-call-content-agents_small-thumb.png\", --><\/p>\n<p>\t\t\t\t},\n\t\t\t\t{\n\t\t\t\t\twistiaID: \"5hxupihbix\", <!-- Required. -->\n\t\t\t\t\ttitle: \"Veeva AI para PromoMats - Spotlight\", <!-- Optional -->\n\t\t\t\t\tdescription: \"Agente de verificaci\u00f3n r\u00e1pida y asistente de PromoMats\", <!-- Optional --><\/p>\n<p>\t\t\t\t},\n\t\t\t\t{\n\t\t\t\twistiaID: \"y0ryo8b9qz\", <!-- Required. -->\n\t\t\t\ttitle: \"Veeva AI para CRM - Overview\", <!-- Optional -->\n\t\t\t\tdescription: \"Orquestaci\u00f3n, segmentaci\u00f3n din\u00e1mica y agentes de IA en Vault CRM\", <!-- Optional -->\n\t\t\t\t},<\/p>\n<p>\t\t\t\t{\n\t\t\t   wistiaID: \"mhi1tfvl5x\", \n\t\t\t   title: \"Veeva AI\", <!-- Optional -->\n\t\t\t   description: \"Configurar agentes de Veeva AI\", <!-- Optional -->\n\t\t\t\t },\n            ];\n            const videoData2 = [\n\t\t\t\t{\n\t\t\t\t\twistiaID: \"28ucth5dgx\", \n\t\t\t\t\ttitle: \"Veeva AI para operaciones cl\u00ednicas\", <!-- Optional -->\n\t\t\t\t\tdescription: \"Agente de admisi\u00f3n y control de calidad de TMF\", <!-- Optional --><\/p>\n<p>\t\t\t\t},\n                                {\n                               wistiaID: \"mhi1tfvl5x\", \n                               title: \"Veeva AI\", <!-- Optional -->\n                               description: \"Configurar agentes de Veeva AI\", <!-- Optional -->\n                                 },\n            ];\n            const videoData3 = [\n                {\n\t\t\t\t\twistiaID: \"g7pihis37d\", \n\t\t\t\t\ttitle: \"Veeva AI para la regulaci\u00f3n\", <!-- Optional -->\n\t\t\t\t\tdescription: \"Agentes de interacci\u00f3n con las autoridades sanitarias\", <!-- Optional --><\/p>\n<p>\t\t\t\t},\n\t\t\t\t{\n\t\t\t\t\twistiaID: \"t66scfawh4\", \n\t\t\t\t\ttitle: \"Veeva AI para la regulaci\u00f3n\", <!-- Optional -->\n\t\t\t\t\tdescription: \"Agente asistente de aplicaciones\", <!-- Optional --><\/p>\n<p>\t\t\t\t},\n                                {\n                               wistiaID: \"mhi1tfvl5x\", \n                               title: \"Veeva AI\", <!-- Optional -->\n                               description: \"Configurar agentes de Veeva AI\", <!-- Optional -->\n                                 },\n            ];<\/p>\n<p>            const videoData4 = [\n                 {\n\t\t\t\t\twistiaID: \"28ucth5dgx\", \n\t\t\t\t\ttitle: \"IA de Veeva para la seguridad\", <!-- Optional -->\n\t\t\t\t\tdescription: \"Agente de admisi\u00f3n de casos y agente de narrativa de casos\", <!-- Optional --><\/p>\n<p>\t\t\t\t},\n                                {\n                               wistiaID: \"mhi1tfvl5x\", \n                               title: \"Veeva AI\", <!-- Optional -->\n                               description: \"Configurar agentes de Veeva AI\", <!-- Optional -->\n                                 },\n            ];<\/p>\n<p>            const videoData5 = [\n        {\n            wistiaID: \"oywvdvsy3b\", \n            title: \"Veeva AI para la calidad\", <!-- Optional -->\n            description: \"Agentes de eventos de calidad y agentes de traducci\u00f3n de documentos\", <!-- Optional --><\/p>\n<p>        },<\/p>\n<p>\t\t\t\t{\n            \twistiaID: \"mhi1tfvl5x\", \n            \ttitle: \"Veeva AI\", <!-- Optional -->\n            \tdescription: \"Configurar agentes de Veeva AI\", <!-- Optional --><\/p>\n<p>        \t\t},\n            ];<\/p>\n<p>            <!-- include your video block data here -->\n            const videoDataList = [\n                videoData1, videoData2, videoData3, videoData4, videoData5\n            ];<\/p>\n<p>            <!-- initialize vidoe block data altogether -->\n            videoBlockIdList.forEach((blockId, index) => {\n                veevaLib.initVideoMultiplePlayerBlock(blockId, videoDataList[index], showVideoInfo);\n            });\n        <\/script> <\/p>\n<p>        <script>\ndocument.addEventListener(\"DOMContentLoaded\", function () {\n  function scrollWithOffset(el, offset = 50) {\n    const y = el.getBoundingClientRect().top + window.scrollY - offset;\n    window.scrollTo({ top: y, behavior: \"smooth\" });\n  }<\/p>\n<p>  <!-- check if there's a hash in the URL -->\n  const hash = window.location.hash.substring(1);\n  if (hash) {\n    const triggerEl = document.querySelector(\n      `[data-bs-toggle=\"pill\"][id=\"${hash}-tab\"]`\n    );\n    if (triggerEl) {\n      const tab = new bootstrap.Tab(triggerEl);\n      tab.show();<\/p>\n<p>      <!-- scroll with offset -->\nsetTimeout(function() {\n      scrollWithOffset(document.querySelector(\"#tablist-1\"), 120);\n}, 1000);\n    }\n  }<\/p>\n<p>  <!-- when switching tabs, update the hash in the URL + scroll -->\n  const tabLinks = document.querySelectorAll('[data-bs-toggle=\"pill\"]');\n  tabLinks.forEach((el) => {\n    el.addEventListener(\"shown.bs.tab\", (event) => {\n      const target = event.target.getAttribute(\"id\");\n      history.replaceState(null, null, '#' + target.replace('-tab', ''));<\/p>\n<p>      <!-- scroll with offset -->\n      scrollWithOffset(document.querySelector(\"#tablist-1\"), 120);\n    });\n  });\n});\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vault AI: IA Ag\u00e9ntica en Vault Platform y Agentes de IA en Aplicaciones Veeva IA profunda que es simple, segura y compliant para empresas de ciencias de la salud de todos los tama\u00f1os. Ver Vault AI en Acci\u00f3n First release planned for December 2025 IA Profunda para Ciencias de la Salud Vault AI is IA&hellip;<\/p>\n","protected":false},"author":217,"featured_media":0,"parent":20394,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/veeva-2024.full-page.php","meta":{"footnotes":""},"class_list":["post-59162","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Veeva AI Overview, 2025 R&amp;D and Quality Summit Keynote &quot;Vault AI consiste en agentes est\u00e1ndar integrados directamente en Vault en todas las aplicaciones para ayudarte a hacer tu trabajo y ser m\u00e1s productivo. Vault AI utiliza los datos y documentos de tu propio Vault, por lo que ser\u00e1 mucho m\u00e1s preciso al responder a tus\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/pantheon.veeva.com\/la\/products\/vault-ai\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Veeva Systems\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Vault AI | Veeva\" \/>\n\t\t<meta property=\"og:description\" content=\"Veeva AI Overview, 2025 R&amp;D and Quality Summit Keynote &quot;Vault AI consiste en agentes est\u00e1ndar integrados directamente en Vault en todas las aplicaciones para ayudarte a hacer tu trabajo y ser m\u00e1s productivo. Vault AI utiliza los datos y documentos de tu propio Vault, por lo que ser\u00e1 mucho m\u00e1s preciso al responder a tus\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/pantheon.veeva.com\/la\/products\/vault-ai\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-04-29T12:10:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-08-31T19:29:19+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Vault AI | Veeva\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Veeva AI Overview, 2025 R&amp;D and Quality Summit Keynote &quot;Vault AI consiste en agentes est\u00e1ndar integrados directamente en Vault en todas las aplicaciones para ayudarte a hacer tu trabajo y ser m\u00e1s productivo. Vault AI utiliza los datos y documentos de tu propio Vault, por lo que ser\u00e1 mucho m\u00e1s preciso al responder a tus\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/products\\\/vault-ai\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/products\\\/#listItem\",\"name\":\"Products\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/products\\\/#listItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/products\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/products\\\/vault-ai\\\/#listItem\",\"name\":\"Vault AI\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/products\\\/vault-ai\\\/#listItem\",\"position\":3,\"name\":\"Vault AI\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/products\\\/#listItem\",\"name\":\"Products\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/#organization\",\"name\":\"Veeva\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/products\\\/vault-ai\\\/#webpage\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/products\\\/vault-ai\\\/\",\"name\":\"Vault AI | Veeva\",\"description\":\"Veeva AI Overview, 2025 R&D and Quality Summit Keynote \\\"Vault AI consiste en agentes est\\u00e1ndar integrados directamente en Vault en todas las aplicaciones para ayudarte a hacer tu trabajo y ser m\\u00e1s productivo. Vault AI utiliza los datos y documentos de tu propio Vault, por lo que ser\\u00e1 mucho m\\u00e1s preciso al responder a tus\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/products\\\/vault-ai\\\/#breadcrumblist\"},\"datePublished\":\"2025-04-29T07:10:25-06:00\",\"dateModified\":\"2026-08-31T13:29:19-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/#website\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/\",\"name\":\"Veeva\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Vault AI | Veeva<\/title>\n\n","aioseo_head_json":{"title":"Vault AI | Veeva","description":"Veeva AI Overview, 2025 R&D and Quality Summit Keynote \"Vault AI consiste en agentes est\u00e1ndar integrados directamente en Vault en todas las aplicaciones para ayudarte a hacer tu trabajo y ser m\u00e1s productivo. Vault AI utiliza los datos y documentos de tu propio Vault, por lo que ser\u00e1 mucho m\u00e1s preciso al responder a tus","canonical_url":"https:\/\/pantheon.veeva.com\/la\/products\/vault-ai\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/pantheon.veeva.com\/la\/products\/vault-ai\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la#listItem","position":1,"name":"Home","item":"https:\/\/pantheon.veeva.com\/la","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/products\/#listItem","name":"Products"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/products\/#listItem","position":2,"name":"Products","item":"https:\/\/pantheon.veeva.com\/la\/products\/","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/products\/vault-ai\/#listItem","name":"Vault AI"},"previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/products\/vault-ai\/#listItem","position":3,"name":"Vault AI","previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/products\/#listItem","name":"Products"}}]},{"@type":"Organization","@id":"https:\/\/pantheon.veeva.com\/la\/#organization","name":"Veeva","url":"https:\/\/pantheon.veeva.com\/la\/"},{"@type":"WebPage","@id":"https:\/\/pantheon.veeva.com\/la\/products\/vault-ai\/#webpage","url":"https:\/\/pantheon.veeva.com\/la\/products\/vault-ai\/","name":"Vault AI | Veeva","description":"Veeva AI Overview, 2025 R&D and Quality Summit Keynote \"Vault AI consiste en agentes est\u00e1ndar integrados directamente en Vault en todas las aplicaciones para ayudarte a hacer tu trabajo y ser m\u00e1s productivo. Vault AI utiliza los datos y documentos de tu propio Vault, por lo que ser\u00e1 mucho m\u00e1s preciso al responder a tus","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/pantheon.veeva.com\/la\/#website"},"breadcrumb":{"@id":"https:\/\/pantheon.veeva.com\/la\/products\/vault-ai\/#breadcrumblist"},"datePublished":"2025-04-29T07:10:25-06:00","dateModified":"2026-08-31T13:29:19-06:00"},{"@type":"WebSite","@id":"https:\/\/pantheon.veeva.com\/la\/#website","url":"https:\/\/pantheon.veeva.com\/la\/","name":"Veeva","inLanguage":"en-US","publisher":{"@id":"https:\/\/pantheon.veeva.com\/la\/#organization"}}]},"og:locale":"en_US","og:site_name":"Veeva Systems","og:type":"article","og:title":"Vault AI | Veeva","og:description":"Veeva AI Overview, 2025 R&amp;D and Quality Summit Keynote &quot;Vault AI consiste en agentes est\u00e1ndar integrados directamente en Vault en todas las aplicaciones para ayudarte a hacer tu trabajo y ser m\u00e1s productivo. Vault AI utiliza los datos y documentos de tu propio Vault, por lo que ser\u00e1 mucho m\u00e1s preciso al responder a tus","og:url":"https:\/\/pantheon.veeva.com\/la\/products\/vault-ai\/","og:image":"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png","og:image:secure_url":"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png","article:published_time":"2025-04-29T12:10:25+00:00","article:modified_time":"2026-08-31T19:29:19+00:00","twitter:card":"summary_large_image","twitter:title":"Vault AI | Veeva","twitter:description":"Veeva AI Overview, 2025 R&amp;D and Quality Summit Keynote &quot;Vault AI consiste en agentes est\u00e1ndar integrados directamente en Vault en todas las aplicaciones para ayudarte a hacer tu trabajo y ser m\u00e1s productivo. Vault AI utiliza los datos y documentos de tu propio Vault, por lo que ser\u00e1 mucho m\u00e1s preciso al responder a tus","twitter:image":"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png"},"aioseo_meta_data":{"post_id":"59162","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2025-04-29 12:08:21","updated":"2026-08-31 20:10:35","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"breadcrumb_settings":null,"seo_analyzer_scan_date":"2026-08-31 19:29:20"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/la\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/la\/products\/\" title=\"Products\">Products<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tVault AI\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/pantheon.veeva.com\/la"},{"label":"Products","link":"https:\/\/pantheon.veeva.com\/la\/products\/"},{"label":"Vault AI","link":"https:\/\/pantheon.veeva.com\/la\/products\/vault-ai\/"}],"_links":{"self":[{"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/pages\/59162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/users\/217"}],"replies":[{"embeddable":true,"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/comments?post=59162"}],"version-history":[{"count":27,"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/pages\/59162\/revisions"}],"predecessor-version":[{"id":60830,"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/pages\/59162\/revisions\/60830"}],"up":[{"embeddable":true,"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/pages\/20394"}],"wp:attachment":[{"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/media?parent=59162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}