{"id":59383,"date":"2025-07-10T12:44:12","date_gmt":"2025-07-10T17:44:12","guid":{"rendered":"https:\/\/www.veeva.com\/la\/?post_type=resources&#038;p=59383"},"modified":"2025-10-24T07:56:14","modified_gmt":"2025-10-24T12:56:14","slug":"anunciando-veeva-ai","status":"publish","type":"resources","link":"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/","title":{"rendered":"Anunciando Veeva AI"},"content":{"rendered":"<p align=\"center\"><i>Una nueva e importante iniciativa incorporar\u00e1 IA a las aplicaciones de Veeva y a la plataforma Veeva Vault para automatizar funciones cr\u00edticas espec\u00edficas de cada sector y mejorar la productividad, desde el \u00e1mbito cl\u00ednico hasta el comercial.<\/i><\/p>\n<p><b class=\"introduction-highlight-text\">PLEASANTON, CA \u2014 29 de abril de 2025 \u2014 <\/b> <a href=\"\/la\/\">Veeva Systems<\/a> (NYSE: VEEV) anunci\u00f3 hoy <a href=\"\/la\/products\/veeva-ai\/\">Veeva AI<\/a>, una nueva e importante iniciativa que incorpora IA a la plataforma Veeva Vault y a las aplicaciones de Veeva para ayudar a las empresas del sector de las ciencias de la vida a automatizar tareas y mejorar la productividad de sus empleados mediante agentes y accesos directos de IA. Veeva AI ofrece una forma r\u00e1pida y eficiente de incorporar agentes de IA espec\u00edficos para cada aplicaci\u00f3n, basados \u200b\u200ben grandes modelos de lenguaje (LLM), en las aplicaciones Veeva existentes y dotar a los usuarios finales de accesos directos de IA. Veeva AI funcionar\u00e1 en todas las aplicaciones de Veeva en todas las \u00e1reas clave, como las cl\u00ednicas, regulatorias, de seguridad, de calidad, m\u00e9dicas y comerciales.<\/p>\n<p> Los Agentes de IA de Veeva se pueden implementar r\u00e1pidamente y con gran impacto, ya que comprenden el contexto de la aplicaci\u00f3n Veeva, cuentan con advertencias y protecciones espec\u00edficas para cada aplicaci\u00f3n y tienen acceso directo y seguro a los datos, documentos y flujos de trabajo de la aplicaci\u00f3n Veeva. Los clientes pueden configurar y ampliar los Agentes de IA de Veeva y crear Agentes de IA personalizados para casos de uso espec\u00edficos de su negocio. Los Agentes de IA se pueden usar a trav\u00e9s de la interfaz de usuario de un chatbot o mediante la API de IA.<\/p>\n<p>Los Atajos de IA de Veeva permiten a los usuarios finales configurar f\u00e1cilmente automatizaciones personales basadas en IA para realizar tareas frecuentes espec\u00edficas del usuario, como ayudar con flujos de trabajo, generar insights o investigar un tema.<\/p>\n<p>\u201cGenAI es un nuevo paradigma en inform\u00e1tica que aumentar\u00e1 significativamente la productividad de los trabajadores del conocimiento\u201d, afirm\u00f3 Peter Gassner, CEO de Veeva. \u201cLas aplicaciones de misi\u00f3n proporcionan datos estructurados, reglas de negocio y flujo de trabajo. Se ejecutan con la velocidad, consistencia y escalabilidad que esperamos de las computadoras. GenAI ofrece la capacidad m\u00e1s parecida a la humana para obtener respuestas e insights de situaciones ambiguas que involucran lenguaje, contexto y amplios conocimientos. La colaboraci\u00f3n entre las aplicaciones de misi\u00f3n y GenAI generar\u00e1 importantes aumentos de productividad\u201d.<\/p>\n<p>Veeva AI es independiente del LLM y compatible con la mayor\u00eda de los modelos de lenguaje principales. Los clientes pueden usar un LLM proporcionado por Veeva o configurar Veeva AI para usar un LLM espec\u00edfico para cada cliente. Independientemente de la implementaci\u00f3n o el LLM que utilice un cliente, Veeva AI mantiene la seguridad de sus datos.<\/p>\n<p\/>\n<p> \u201cNuestros clientes conf\u00edan en las aplicaciones de Veeva para algunos de sus procesos m\u00e1s cr\u00edticos y espec\u00edficos de la industria, desde el \u00e1mbito cl\u00ednico hasta el comercial. Quieren usar IA para aumentar la productividad y, en \u00faltima instancia, que los tratamientos lleguen a los pacientes m\u00e1s r\u00e1pidamente\u201d, afirm\u00f3 Peter Gassner, director ejecutivo. \u201cIncorporar Veeva AI a nuestras aplicaciones principales contribuir\u00e1 a que la IA sea sencilla, segura y compatible con la normativa para empresas de ciencias de la vida de todos los tama\u00f1os\u201d.<\/p>\n<p>El primer lanzamiento de Veeva AI est\u00e1 previsto para diciembre de 2025 y tendr\u00e1 licencia a nivel de Vault con una tarifa de suscripci\u00f3n simple y razonable para fomentar una adopci\u00f3n amplia y reflexiva en la industria.<\/p>\n<p><b>Acerca de Veeva Systems<\/b><br \/>\nVeeva es l\u00edder mundial en software en la nube para la industria de las ciencias de la vida. Comprometida con la innovaci\u00f3n, la excelencia de sus productos y el \u00e9xito de sus clientes, Veeva presta servicio a m\u00e1s de 1000 clientes, desde las compa\u00f1\u00edas biofarmac\u00e9uticas m\u00e1s grandes del mundo hasta empresas biotecnol\u00f3gicas emergentes. Como <a href=\"https:\/\/www.veeva.com\/pbc\/\">corporaci\u00f3n de beneficio p\u00fablico<\/a>, Veeva se compromete a equilibrar los intereses de todas las partes interesadas, incluyendo clientes, empleados, accionistas y las industrias a las que presta servicio. Para m\u00e1s informaci\u00f3n, visite <a href=\"https:\/\/www.veeva.com\/la\/\">veeva.com\/la<\/a>\n<\/p>\n<p><b>Declaraciones prospectivas de Veeva<\/b><br \/>\nEste comunicado contiene declaraciones prospectivas sobre los productos y servicios de Veeva y los resultados o beneficios esperados del uso de nuestros productos y servicios, incluyendo algunas de nuestras nuevas soluciones y aplicaciones que a\u00fan est\u00e1n en desarrollo o no est\u00e1n disponibles para el p\u00fablico general. Estas declaraciones se basan en nuestras expectativas actuales. Los resultados reales, la disponibilidad y cualquier evento futuro relacionado con estos productos y servicios pueden diferir sustancialmente de los proporcionados en este comunicado, y no asumimos ninguna obligaci\u00f3n de actualizar dichas declaraciones. Existen numerosos riesgos que podr\u00edan afectar negativamente a nuestros resultados, incluyendo los riesgos e incertidumbres revelados en nuestra presentaci\u00f3n en el Formulario 10-K para el a\u00f1o fiscal que finaliz\u00f3 el 31 de enero de 2025, que puede encontrar <a href=\"https:\/\/www.sec.gov\/ix?doc=\/Archives\/edgar\/data\/0001393052\/000139305225000022\/veev-20250131.htm#i7e129a0ad48d459ea13c21cd7e2de073_124\" target=\"_blank\" rel=\"noreferrer noopener\">aqui<\/a> (en las p\u00e1ginas 9 y 10 encontrar\u00e1 un resumen de los riesgos que podr\u00edan afectar a nuestro negocio), y en nuestras presentaciones posteriores ante la SEC, a las que puede acceder en <a href=\"https:\/\/www.sec.gov\/\" rel=\"noopener\" target=\"_blank\">sec.gov<\/a>.\n<\/p>\n<\/p>\n<p><center><\/p>\n<p>###<\/p>\n<p><\/center><\/p>\n<p><strong>Contacto:<\/strong> <\/p>\n<p>Maria Scurry<br \/>\nVeeva Systems<br \/>\n781-366-7617<br \/>\n<a href=\"mailto:maria.scurry@veeva.com\">maria.scurry@veeva.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una nueva e importante iniciativa incorporar\u00e1 IA a las aplicaciones de Veeva y a la plataforma Veeva Vault para automatizar funciones cr\u00edticas espec\u00edficas de cada sector y mejorar la productividad, desde el \u00e1mbito cl\u00ednico hasta el comercial. PLEASANTON, CA \u2014 29 de abril de 2025 \u2014 Veeva Systems (NYSE: VEEV) anunci\u00f3 hoy Veeva AI, una&hellip;<\/p>\n","protected":false},"featured_media":59695,"parent":0,"template":"","class_list":["post-59383","resources","type-resources","status-publish","has-post-thumbnail","hentry","resource-type-press-release"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Una nueva e importante iniciativa incorporar\u00e1 IA a las aplicaciones de Veeva y a la plataforma Veeva Vault para automatizar funciones cr\u00edticas espec\u00edficas de cada sector y mejorar la productividad, desde el \u00e1mbito cl\u00ednico hasta el comercial. PLEASANTON, CA \u2014 29 de abril de 2025 \u2014 Veeva Systems (NYSE: VEEV) anunci\u00f3 hoy Veeva AI, una\" \/>\n\t<meta name=\"robots\" content=\"noindex, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Veeva Systems\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Anunciando Veeva AI | Veeva\" \/>\n\t\t<meta property=\"og:description\" content=\"Una nueva e importante iniciativa incorporar\u00e1 IA a las aplicaciones de Veeva y a la plataforma Veeva Vault para automatizar funciones cr\u00edticas espec\u00edficas de cada sector y mejorar la productividad, desde el \u00e1mbito cl\u00ednico hasta el comercial. PLEASANTON, CA \u2014 29 de abril de 2025 \u2014 Veeva Systems (NYSE: VEEV) anunci\u00f3 hoy Veeva AI, una\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-07-10T17:44:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-10-24T12:56:14+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Anunciando Veeva AI | Veeva\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Una nueva e importante iniciativa incorporar\u00e1 IA a las aplicaciones de Veeva y a la plataforma Veeva Vault para automatizar funciones cr\u00edticas espec\u00edficas de cada sector y mejorar la productividad, desde el \u00e1mbito cl\u00ednico hasta el comercial. PLEASANTON, CA \u2014 29 de abril de 2025 \u2014 Veeva Systems (NYSE: VEEV) anunci\u00f3 hoy Veeva AI, una\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resources\\\/anunciando-veeva-ai\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resources\\\/#listItem\",\"name\":\"Resources\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resources\\\/#listItem\",\"position\":2,\"name\":\"Resources\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resources\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resource-type\\\/press-release\\\/#listItem\",\"name\":\"Press Releases\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resource-type\\\/press-release\\\/#listItem\",\"position\":3,\"name\":\"Press Releases\",\"item\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resource-type\\\/press-release\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resources\\\/anunciando-veeva-ai\\\/#listItem\",\"name\":\"Anunciando Veeva AI\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resources\\\/#listItem\",\"name\":\"Resources\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resources\\\/anunciando-veeva-ai\\\/#listItem\",\"position\":4,\"name\":\"Anunciando Veeva AI\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resource-type\\\/press-release\\\/#listItem\",\"name\":\"Press Releases\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/#organization\",\"name\":\"Veeva\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resources\\\/anunciando-veeva-ai\\\/#webpage\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resources\\\/anunciando-veeva-ai\\\/\",\"name\":\"Anunciando Veeva AI | Veeva\",\"description\":\"Una nueva e importante iniciativa incorporar\\u00e1 IA a las aplicaciones de Veeva y a la plataforma Veeva Vault para automatizar funciones cr\\u00edticas espec\\u00edficas de cada sector y mejorar la productividad, desde el \\u00e1mbito cl\\u00ednico hasta el comercial. PLEASANTON, CA \\u2014 29 de abril de 2025 \\u2014 Veeva Systems (NYSE: VEEV) anunci\\u00f3 hoy Veeva AI, una\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resources\\\/anunciando-veeva-ai\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/imagem-capa-veeva-ai-anuncio2.jpg\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resources\\\/anunciando-veeva-ai\\\/#mainImage\",\"width\":320,\"height\":220,\"caption\":\"imagem capa veeva ai anuncio2\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/resources\\\/anunciando-veeva-ai\\\/#mainImage\"},\"datePublished\":\"2025-07-10T12:44:12-06:00\",\"dateModified\":\"2025-10-24T07:56:14-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/#website\",\"url\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/\",\"name\":\"Veeva\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/pantheon.veeva.com\\\/la\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Anunciando Veeva AI | Veeva<\/title>\n\n","aioseo_head_json":{"title":"Anunciando Veeva AI | Veeva","description":"Una nueva e importante iniciativa incorporar\u00e1 IA a las aplicaciones de Veeva y a la plataforma Veeva Vault para automatizar funciones cr\u00edticas espec\u00edficas de cada sector y mejorar la productividad, desde el \u00e1mbito cl\u00ednico hasta el comercial. PLEASANTON, CA \u2014 29 de abril de 2025 \u2014 Veeva Systems (NYSE: VEEV) anunci\u00f3 hoy Veeva AI, una","canonical_url":"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/","robots":"noindex, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la#listItem","position":1,"name":"Home","item":"https:\/\/pantheon.veeva.com\/la","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/resources\/#listItem","name":"Resources"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/resources\/#listItem","position":2,"name":"Resources","item":"https:\/\/pantheon.veeva.com\/la\/resources\/","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/resource-type\/press-release\/#listItem","name":"Press Releases"},"previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/resource-type\/press-release\/#listItem","position":3,"name":"Press Releases","item":"https:\/\/pantheon.veeva.com\/la\/resource-type\/press-release\/","nextItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/#listItem","name":"Anunciando Veeva AI"},"previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/resources\/#listItem","name":"Resources"}},{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/#listItem","position":4,"name":"Anunciando Veeva AI","previousItem":{"@type":"ListItem","@id":"https:\/\/pantheon.veeva.com\/la\/resource-type\/press-release\/#listItem","name":"Press Releases"}}]},{"@type":"Organization","@id":"https:\/\/pantheon.veeva.com\/la\/#organization","name":"Veeva","url":"https:\/\/pantheon.veeva.com\/la\/"},{"@type":"WebPage","@id":"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/#webpage","url":"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/","name":"Anunciando Veeva AI | Veeva","description":"Una nueva e importante iniciativa incorporar\u00e1 IA a las aplicaciones de Veeva y a la plataforma Veeva Vault para automatizar funciones cr\u00edticas espec\u00edficas de cada sector y mejorar la productividad, desde el \u00e1mbito cl\u00ednico hasta el comercial. PLEASANTON, CA \u2014 29 de abril de 2025 \u2014 Veeva Systems (NYSE: VEEV) anunci\u00f3 hoy Veeva AI, una","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/pantheon.veeva.com\/la\/#website"},"breadcrumb":{"@id":"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/pantheon.veeva.com\/la\/wp-content\/uploads\/2025\/07\/imagem-capa-veeva-ai-anuncio2.jpg","@id":"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/#mainImage","width":320,"height":220,"caption":"imagem capa veeva ai anuncio2"},"primaryImageOfPage":{"@id":"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/#mainImage"},"datePublished":"2025-07-10T12:44:12-06:00","dateModified":"2025-10-24T07:56:14-06:00"},{"@type":"WebSite","@id":"https:\/\/pantheon.veeva.com\/la\/#website","url":"https:\/\/pantheon.veeva.com\/la\/","name":"Veeva","inLanguage":"en-US","publisher":{"@id":"https:\/\/pantheon.veeva.com\/la\/#organization"}}]},"og:locale":"en_US","og:site_name":"Veeva Systems","og:type":"article","og:title":"Anunciando Veeva AI | Veeva","og:description":"Una nueva e importante iniciativa incorporar\u00e1 IA a las aplicaciones de Veeva y a la plataforma Veeva Vault para automatizar funciones cr\u00edticas espec\u00edficas de cada sector y mejorar la productividad, desde el \u00e1mbito cl\u00ednico hasta el comercial. PLEASANTON, CA \u2014 29 de abril de 2025 \u2014 Veeva Systems (NYSE: VEEV) anunci\u00f3 hoy Veeva AI, una","og:url":"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/","og:image":"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png","og:image:secure_url":"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png","article:published_time":"2025-07-10T17:44:12+00:00","article:modified_time":"2025-10-24T12:56:14+00:00","twitter:card":"summary_large_image","twitter:title":"Anunciando Veeva AI | Veeva","twitter:description":"Una nueva e importante iniciativa incorporar\u00e1 IA a las aplicaciones de Veeva y a la plataforma Veeva Vault para automatizar funciones cr\u00edticas espec\u00edficas de cada sector y mejorar la productividad, desde el \u00e1mbito cl\u00ednico hasta el comercial. PLEASANTON, CA \u2014 29 de abril de 2025 \u2014 Veeva Systems (NYSE: VEEV) anunci\u00f3 hoy Veeva AI, una","twitter:image":"https:\/\/www.veeva.com\/wp-content\/uploads\/2020\/08\/Generic-Social-Banners_v3_Veeva-Generic.png"},"aioseo_meta_data":{"post_id":"59383","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","created":"2025-07-10 17:40:21","updated":"2026-08-25 06:18:46","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":"2026-08-20 23:40:36"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/la\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/la\/resources\/\" title=\"Resources\">Resources<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/pantheon.veeva.com\/la\/resource-type\/press-release\/\" title=\"Press Releases\">Press Releases<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tAnunciando Veeva AI\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/pantheon.veeva.com\/la"},{"label":"Resources","link":"https:\/\/pantheon.veeva.com\/la\/resources\/"},{"label":"Press Releases","link":"https:\/\/pantheon.veeva.com\/la\/resource-type\/press-release\/"},{"label":"Anunciando Veeva AI","link":"https:\/\/pantheon.veeva.com\/la\/resources\/anunciando-veeva-ai\/"}],"_links":{"self":[{"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/resources\/59383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/types\/resources"}],"version-history":[{"count":1,"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/resources\/59383\/revisions"}],"predecessor-version":[{"id":59384,"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/resources\/59383\/revisions\/59384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/media\/59695"}],"wp:attachment":[{"href":"https:\/\/pantheon.veeva.com\/la\/wp-json\/wp\/v2\/media?parent=59383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}